[{"id":29160,"date":"2026-01-23T11:07:12","date_gmt":"2026-01-23T19:07:12","guid":{"rendered":"https:\/\/seiu775.org\/?page_id=29160"},"modified":"2026-07-06T14:53:53","modified_gmt":"2026-07-06T21:53:53","slug":"jobs-2","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/jobs-2\/","title":{"rendered":"Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Solicite ahora empleo en Washington, Alaska y Montana<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQuiere formar parte de un equipo diverso que lucha por el cambio, la justicia y la equidad para las familias trabajadoras? \u00a1Entonces SEIU&nbsp;775 es el lugar para usted! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/seiu775.rec.pro.ukg.net\/SEI1501SEAU\/JobBoard\/6878e0c2-5089-4533-b419-f69cd94b4dda\/?q=&amp;o=postedDateDesc&amp;w=&amp;wc=&amp;we=&amp;wpst=\"><strong>Ver ofertas de empleo actuales &#8211; Solicitantes externos<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/welcome-us.ukg.net\/u\/login?state=hqFo2SBqQkk3M19tMG9yNVZxRE9XaExQR0U4c2R4OURINlVsTqFur3VuaXZlcnNhbC1sb2dpbqN0aWTZIHczbEY4eXJLMWNKdE9xLUhZemY4WV9xM0FGNUVrNkJCo2NpZNkkZDBkOGIxNmItZGVmYi00NzYyLTg3YTItMmYxOWU0ODFlYzNmpW9yZ2lktG9yZ19IZEdZYnA2bjNEWUZnaFVWp29yZ25hbWW3NjIxODMxMF9zZWl1Xzc3NV9wcmQzMDI&amp;ui_locales=en\"><strong>Ver ofertas de empleo actuales &#8211; Empleados de SEIU&nbsp;775 <\/strong><\/a><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-97ed9c64 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1087\" height=\"815\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4.png\" alt=\"\" class=\"wp-image-29278\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4.png 1087w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4-300x225.png 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4-1024x768.png 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4-768x576.png 768w\" sizes=\"auto, (max-width: 1087px) 100vw, 1087px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando empec\u00e9, no hubiera imaginado que me enamorar\u00eda del trabajo de la manera en que lo hice\u201d. <strong>-Lucy V\u00e1zquez Mart\u00ednez, directora de atenci\u00f3n domiciliaria de Field (Equipo de Trabajo de Campo) de SEIU&nbsp;775, desde el 2013<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-524f8de7 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1087\" height=\"815\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/2-1.png\" alt=\"\" class=\"wp-image-29284\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/2-1.png 1087w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/2-1-300x225.png 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/2-1-1024x768.png 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/2-1-768x576.png 768w\" sizes=\"auto, (max-width: 1087px) 100vw, 1087px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi lo que est\u00e1 buscando es difundir amor, aceptar a los dem\u00e1s y ayudarlos, este es el lugar ideal para usted\u201d. <strong>-Dilnoza \u201cD\u201d Khabibova, representante del Member Resource Center (Centro de Informaci\u00f3n para Miembros) de SEIU&nbsp;775, desde el 2024<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-97ed9c64 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1087\" height=\"815\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1.png\" alt=\"\" class=\"wp-image-29291\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1.png 1087w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1-300x225.png 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1-1024x768.png 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1-768x576.png 768w\" sizes=\"auto, (max-width: 1087px) 100vw, 1087px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe siento muy privilegiado por hacer este trabajo, ya que nuestros miembros son l\u00edderes en sus comunidades.&nbsp; Honestamente, son personas realmente incre\u00edbles\u201d.<strong> &#8211; Phoenix Moreno, coordinador de Pol\u00edticas y Defensa de SEIU&nbsp;775, desde el 2022<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-97ed9c64 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1087\" height=\"815\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1-1.png\" alt=\"\" class=\"wp-image-29297\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1-1.png 1087w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1-1-300x225.png 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1-1-1024x768.png 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-1-1-768x576.png 768w\" sizes=\"auto, (max-width: 1087px) 100vw, 1087px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa manera en la que he recibido mentor\u00eda desde que llegu\u00e9 aqu\u00ed ha sido incre\u00edble. Mis gerentes, directores, compa\u00f1eros de trabajo, todos est\u00e1n siempre dispuestos a ayudar\u201d. <strong>&#8211; Miguel Bautista, analista de Investigaci\u00f3n y Pol\u00edticas de SEIU&nbsp;775, desde el 2021<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qui\u00e9nes somos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">SEIU&nbsp;775 es una uni\u00f3n laboral con 60,000&nbsp;trabajadores que brindan atenci\u00f3n a los miembros m\u00e1s vulnerables de nuestra comunidad: personas con discapacidades, adultos mayores, entre otros. Al trabajar aqu\u00ed, est\u00e1 ayudando a estos cuidadores valiosos a cuidar de s\u00ed mismos y de sus familias, as\u00ed como a construir poder pol\u00edtico y econ\u00f3mico. <strong><a href=\"https:\/\/workforcenow.adp.com\/mascsr\/default\/mdf\/recruitment\/recruitment.html?cid=24b6f6f3-6543-4e63-83a0-dc07b7cd758a\">Obtenga m\u00e1s informaci\u00f3n sobre SEIU&nbsp;775 y nuestros valores<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"616\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/08\/SEIU775BG_kb211124_S-Harders_05-scaled-e1650992145284-1-768x616-2.webp\" alt=\"\" class=\"wp-image-29171 size-full\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/08\/SEIU775BG_kb211124_S-Harders_05-scaled-e1650992145284-1-768x616-2.webp 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/08\/SEIU775BG_kb211124_S-Harders_05-scaled-e1650992145284-1-768x616-2-300x241.webp 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">\u201cTrabaje con nosotros si quiere hacer el bien a otros. El trabajo no siempre es f\u00e1cil, pero siempre es importante\u201d.<br><strong>&#8211; Sterling Harders, presidenta de SEIU&nbsp;775<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Trabajar en SEIU&nbsp;775 marca toda la diferencia<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/7-1024x768.png\" alt=\"\" class=\"wp-image-29321\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/7-1024x768.png 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/7-300x225.png 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/7-768x576.png 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/7.png 1087w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Defensa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, el equipo de SEIU&nbsp;775 empoder\u00f3 a nuestros miembros de Montana para que hicieran cabildeo ante sus legisladores, por lo que obtuvieron mejoras significativas tanto para los cuidadores como para sus clientes vulnerables.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-stretch is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/8-1-1024x768.png\" alt=\"\" class=\"wp-image-29339\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/8-1-1024x768.png 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/8-1-300x225.png 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/8-1-768x576.png 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/8-1.png 1087w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Organizaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo de SEIU&nbsp;775 ayud\u00f3 a miles de nuestros miembros que trabajan en nursing homes (asilos para ancianos) a luchar por y obtener aumentos salariales significativos de hasta el 20&nbsp;%.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-2-1024x768.png\" alt=\"\" class=\"wp-image-29350\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-2-1024x768.png 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-2-300x225.png 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-2-768x576.png 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/Headshots-for-SEIU-775-Website-2.png 1087w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Servicios para miembros<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los d\u00edas, el equipo de SEIU&nbsp;775 ayuda a los cuidadores a cuidar de s\u00ed mismos y de sus familias a trav\u00e9s de nuestro Member Resource Center (Centro de Informaci\u00f3n para Miembros), en el que hablamos 17&nbsp;idiomas diferentes.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 id=\"job-postings\" class=\"wp-block-heading\">Beneficios<\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:auto 23%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">SEIU&nbsp;775 ofrece pagos competitivos, grandes beneficios y oportunidades de crecimiento. Los beneficios incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Paid Time Off (tiempo de vacaciones pagadas): <\/strong>Vacaciones, feriados y d\u00edas de licencia por enfermedad generosos<\/li>\n\n\n\n<li><strong>Seguro: <\/strong>Seguro m\u00e9dico, dental, de la vista y de vida cubierto en su totalidad para usted <strong>y su familia<\/strong><\/li>\n\n\n\n<li><strong>Jubilaci\u00f3n:<\/strong> Plan de pensi\u00f3n con beneficios definidos y 401(k) opcional<\/li>\n\n\n\n<li><strong>Trabajo desde casa:<\/strong> Cr\u00e9dito disponible<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Y m\u00e1s!<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"426\" height=\"586\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-17-at-12.40.09.png\" alt=\"\" class=\"wp-image-29177 size-full\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-17-at-12.40.09.png 426w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-17-at-12.40.09-218x300.png 218w\" sizes=\"auto, (max-width: 426px) 100vw, 426px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Declaraci\u00f3n antirracismo y antiopresi\u00f3n de SEIU&nbsp;775<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La fuerza laboral de los cuidadores es mayoritariamente femenina y desproporcionadamente mujeres de raza negra, ind\u00edgenas, asi\u00e1ticas, latinas, de color e inmigrantes. Precisamente por ser quienes somos, el trabajo del servicio de cuidados ha sido excluido de muchas protecciones b\u00e1sicas en el lugar de trabajo. Los cuidadores siguen luchando por ganar un salario digno y respeto debido al racismo y sexismo sist\u00e9micos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En SEIU&nbsp;775, nuestra misi\u00f3n es unir las fuerzas de todos los cuidadores con el fin de mejorar nuestras vidas y las de aquellas personas bajo nuestro cuidado, as\u00ed como marcar el camino hacia un mundo m\u00e1s justo y equitativo. No podemos cumplir nuestra misi\u00f3n y conseguir justicia econ\u00f3mica si no trabajamos para abolir el racismo sist\u00e9mico y otras formas de prejuicio y opresi\u00f3n.&nbsp; Nos comprometemos a impulsar el cambio institucional necesario para abolir estas estructuras, tanto dentro de nuestra organizaci\u00f3n como en la sociedad en general. Seguiremos trabajando para luchar contra el prejuicio, la opresi\u00f3n y el racismo donde sea que los encontremos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solicite ahora empleo en Washington, Alaska y Montana \u00bfQuiere formar parte de un equipo diverso que lucha por el cambio, la justicia y la equidad para las familias trabajadoras? \u00a1Entonces SEIU&nbsp;775 es el lugar para usted! Ver ofertas de empleo actuales &#8211; Solicitantes externos Ver ofertas de empleo actuales &#8211; Empleados de SEIU&nbsp;775 \u201cCuando empec\u00e9, [&hellip;]<\/p>\n","protected":false},"author":5913,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-with-login-section.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-29160","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad - SEIU 775<\/title>\n<meta name=\"description\" content=\"\u00bfLe interesa trabajar en la uni\u00f3n de cuidadores, SEIU\u00a0775? Obtenga m\u00e1s informaci\u00f3n acerca de nuestras ofertas de empleo actuales y post\u00falese aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/es\/jobs-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"\u00bfLe interesa trabajar en la uni\u00f3n de cuidadores, SEIU\u00a0775? Obtenga m\u00e1s informaci\u00f3n acerca de nuestras ofertas de empleo actuales y post\u00falese aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/es\/jobs-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T21:53:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1087\" \/>\n\t<meta property=\"og:image:height\" content=\"815\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/jobs-2\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/es\\\/jobs-2\\\/\",\"name\":\"Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/jobs-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/jobs-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/4.png\",\"datePublished\":\"2026-01-23T19:07:12+00:00\",\"dateModified\":\"2026-07-06T21:53:53+00:00\",\"description\":\"\u00bfLe interesa trabajar en la uni\u00f3n de cuidadores, SEIU\u00a0775? Obtenga m\u00e1s informaci\u00f3n acerca de nuestras ofertas de empleo actuales y post\u00falese aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/jobs-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/es\\\/jobs-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/jobs-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/4.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/4.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/jobs-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad - SEIU 775","description":"\u00bfLe interesa trabajar en la uni\u00f3n de cuidadores, SEIU\u00a0775? Obtenga m\u00e1s informaci\u00f3n acerca de nuestras ofertas de empleo actuales y post\u00falese aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/es\/jobs-2\/","og_locale":"es_ES","og_type":"article","og_title":"Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad - SEIU 775","og_description":"\u00bfLe interesa trabajar en la uni\u00f3n de cuidadores, SEIU\u00a0775? Obtenga m\u00e1s informaci\u00f3n acerca de nuestras ofertas de empleo actuales y post\u00falese aqu\u00ed.","og_url":"https:\/\/seiu775.org\/es\/jobs-2\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2026-07-06T21:53:53+00:00","og_image":[{"width":1087,"height":815,"url":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/es\/jobs-2\/","url":"https:\/\/seiu775.org\/es\/jobs-2\/","name":"Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seiu775.org\/es\/jobs-2\/#primaryimage"},"image":{"@id":"https:\/\/seiu775.org\/es\/jobs-2\/#primaryimage"},"thumbnailUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4.png","datePublished":"2026-01-23T19:07:12+00:00","dateModified":"2026-07-06T21:53:53+00:00","description":"\u00bfLe interesa trabajar en la uni\u00f3n de cuidadores, SEIU\u00a0775? Obtenga m\u00e1s informaci\u00f3n acerca de nuestras ofertas de empleo actuales y post\u00falese aqu\u00ed.","breadcrumb":{"@id":"https:\/\/seiu775.org\/es\/jobs-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/es\/jobs-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/es\/jobs-2\/#primaryimage","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/09\/4.png"},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/es\/jobs-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"Trabaje en SEIU&nbsp;775 y marque la diferencia en su comunidad"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/29160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/5913"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=29160"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/29160\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=29160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":29869,"date":"2025-12-22T10:47:42","date_gmt":"2025-12-22T18:47:42","guid":{"rendered":"https:\/\/seiu775.org\/agenda-legislativa-de-washington-para-el-2026\/"},"modified":"2026-03-27T10:29:07","modified_gmt":"2026-03-27T17:29:07","slug":"2026waleg","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/2026waleg\/","title":{"rendered":"Agenda legislativa de Washington para el 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los cuidadores no dimos marcha atr\u00e1s en ning\u00fan momento durante la sesi\u00f3n legislativa de Washington 2026.&nbsp;<strong>Nos enfrentamos a grandes dificultades y amenazas de recortes devastadores a la atenci\u00f3n a largo plazo, pero nos manifestamos con fuerza.&nbsp;<\/strong>Llevamos a cabo congregaciones en Olympia, Spokane, Yakima y Bellingham; vestimos al Capitolio de morado durante tres&nbsp;Purple&nbsp;Presences; y alzamos la voz en representaci\u00f3n de la igualdad tributaria, los derechos de los&nbsp;domestic&nbsp;workers&nbsp;(trabajadores dom\u00e9sticos), la protecci\u00f3n de la atenci\u00f3n m\u00e9dica de los inmigrantes y m\u00e1s.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los miembros de SEIU\u202f775 colmamos las l\u00edneas telef\u00f3nicas de los legisladores, les enviamos miles de correos electr\u00f3nicos y testificamos en muchas audiencias para asegurarnos de que los legisladores no pudieran ignorar nuestras voces y prioridades.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-1024x683.jpg\" alt=\"\" class=\"wp-image-30322\" style=\"aspect-ratio:1.4992905143101924;width:772px;height:auto\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-1024x683.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-300x200.jpg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-768x512.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-1536x1024.jpg 1536w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a nuestro arduo trabajo, hoy podemos celebrar victorias hist\u00f3ricas para los cuidadores.<strong>&nbsp;Juntos:&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Evitamos que se recortara la atenci\u00f3n a m\u00e1s de\u00a0<strong>6,000<\/strong>\u202fclientes de atenci\u00f3n a largo plazo. Gracias al s\u00f3lido liderazgo de los cuidadores, el estado de Washington intervendr\u00e1 para proteger a miles de personas que hubieran perdido la atenci\u00f3n a largo plazo y la atenci\u00f3n m\u00e9dica de las que dependen.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pusimos al sistema tributario de nuestro estado un paso m\u00e1s cerca de ser m\u00e1s justo para las personas trabajadoras al\u00a0<strong>aprobar el impuesto a los millonarios.<\/strong>\u00a0Adem\u00e1s de generar miles de millones de d\u00f3lares para servicios esenciales, este proyecto de ley\u00a0le\u00a0pone fin a los impuestos sobre las ventas de pa\u00f1ales y medicamentos de venta libre, junto con la ampliaci\u00f3n del\u00a0Working\u00a0Families\u00a0Tax\u00a0Credit\u00a0(cr\u00e9dito fiscal para las familias trabajadoras).\u00a0\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aprobamos de manera un\u00e1nime la legislaci\u00f3n para garantizar\u00a0<strong>el mismo pago y los mismos beneficios para los\u00a0agency\u00a0providers\u00a0(proveedores de la agencia).<\/strong>\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al trabajar siempre unidos en la lucha, ayudamos a aprobar la\u00a0<strong>carta de derechos de los\u00a0domestic\u00a0workers\u00a0(trabajadores dom\u00e9sticos)\u00a0<\/strong>y la\u00a0<strong>Immigrant\u00a0Worker\u00a0Protection\u00a0Act\u00a0(Ley de protecci\u00f3n del trabajador inmigrante).<\/strong>\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conseguimos cambios clave en materia de financiaci\u00f3n y pol\u00edtica para\u00a0<strong>lograr que la vivienda y los servicios p\u00fablicos sean m\u00e1s asequibles<\/strong>\u00a0para las personas en todo nuestro estado.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">No lo ganamos todo. A\u00fan nos esperan grandes batallas en el futuro para proteger la atenci\u00f3n a los inmigrantes que est\u00e1n bajo el ataque de los pol\u00edticos federales. Seguiremos luchando para responsabilizar a los&nbsp;nursing&nbsp;homes&nbsp;(asilos para ancianos) y a los centros de servicios de vida con apoyo para que les paguen a los trabajadores un salario justo. Colaboraremos y elegiremos a pol\u00edticos que apoyen a los cuidadores, y votaremos en contra de aquellos que no lo hagan.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Somos m\u00e1s fuertes que estos ataques. Juntos somos m\u00e1s fuertes.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo lo que ganamos es prueba de que nuestras voces son poderosas; incluso en un a\u00f1o dif\u00edcil, logramos avanzar mucho aqu\u00ed en el estado de Washington.<strong>&nbsp;<\/strong>Es cierto que a\u00fan nos esperan duras batallas en el futuro;&nbsp;<strong>sin embargo, por eso es m\u00e1s importante que nunca que celebremos, nos aferremos a esas victorias y sigamos luchando.<\/strong>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"stop-the-cuts\">Nuestro objetivo: <strong>Detener los recortes:<\/strong> proteger la atenci\u00f3n a largo plazo, la atenci\u00f3n m\u00e9dica, los programas de alimentos y los servicios comunitarios esenciales frente a los recortes&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El presupuesto final financia la atenci\u00f3n a largo plazo y la atenci\u00f3n m\u00e9dica para\u00a0<strong>1,191<\/strong>\u202finmigrantes que, de otro modo, habr\u00edan perdido estos servicios debido a los crueles recortes federales a Medicaid previstos en el HR\u202f1. Hemos creado un camino para financiar la atenci\u00f3n de las\u00a0<strong>1,509<\/strong>\u202fpersonas restantes que podr\u00edan quedarse sin ella, y seguiremos abogando por esta financiaci\u00f3n. Tambi\u00e9n logramos detener una propuesta de recorte en la elegibilidad para recibir atenci\u00f3n a largo plazo incluida en el presupuesto del gobernador, lo que evit\u00f3 que otros\u00a0<strong>5,000<\/strong>\u202fclientes perdieran este servicio.\u00a0\u00a0\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"make-caregiving-a-good-career\">Nuestro objetivo: Hacer del servicio de cuidados una profesi\u00f3n de calidad<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Garantizar el mismo pago y los mismos beneficios para los&nbsp;agency&nbsp;providers&nbsp;(proveedores de la agencia) de atenci\u00f3n domiciliaria<\/strong>: El proyecto de ley de&nbsp;agency&nbsp;parity, que garantiza el mismo pago y los mismos beneficios para los&nbsp;agency&nbsp;providers&nbsp;(proveedores de la agencia) de atenci\u00f3n domiciliaria, fue aprobado por unanimidad en la&nbsp;legislatura. Ya sea que los proveedores de atenci\u00f3n domiciliaria est\u00e9n empleados por CDWA o por una agencia, merecemos recibir el mismo pago por el mismo trabajo y tener acceso a la misma capacitaci\u00f3n y a los mismos beneficios de atenci\u00f3n m\u00e9dica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Invertir en la fuerza laboral de los&nbsp;nursing&nbsp;homes&nbsp;(asilos para ancianos)<\/strong>: La financiaci\u00f3n para los&nbsp;nursing&nbsp;homes&nbsp;(asilos para ancianos), conocida como el reajuste, se llevar\u00e1 a cabo en el 2026 como estaba programada. Seguiremos luchando para que se incluya una disposici\u00f3n imprescindible que garantice qu\u00e9 porcentaje de esta financiaci\u00f3n se destina directamente a los salarios y beneficios de los trabajadores de&nbsp;nursing&nbsp;homes&nbsp;(asilos para ancianos).&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Poner fin a las restricciones innecesarias en los servicios de vida con apoyo<\/strong>: Pudimos ponerle fin al Programa de Protecci\u00f3n Comunitaria, que era excesivamente restrictivo y obligaba a las personas que reciben servicios de vida con apoyo a renunciar a sus derechos a la libertad de movimiento y a la privacidad solo para poder recibir el cuidado que necesitan. El CPP incluso imped\u00eda que los cuidadores de servicios de vida con apoyo se unieran a nuestra Uni\u00f3n, ya que nos clasifica err\u00f3neamente como \u201cguardias\u201d.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01741-1-1024x683.jpg\" alt=\"\" class=\"wp-image-30328\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01741-1-1024x683.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01741-1-300x200.jpg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01741-1-768x512.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01741-1-1536x1024.jpg 1536w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01741-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"tax-the-ultra-wealthy\">Nuestro objetivo: Cobrar impuestos a los m\u00e1s ricos para arreglar nuestro sistema fiscal ca\u00f3tico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hacer que los millonarios paguen lo que les corresponde:&nbsp;<\/strong>La legislatura aprob\u00f3 el hist\u00f3rico impuesto a los millonarios, lo que acerca a nuestro estado un paso m\u00e1s a un sistema tributario m\u00e1s justo para las personas trabajadoras. Al conseguir la aprobaci\u00f3n del impuesto a los millonarios, logramos:&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Obtener miles de millones de d\u00f3lares para invertir en atenci\u00f3n m\u00e9dica, atenci\u00f3n a largo plazo, educaci\u00f3n y otros servicios p\u00fablicos esenciales.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ponerle\u00a0fin a los impuestos sobre las ventas de pa\u00f1ales, medicamentos de venta libre y productos de higiene y aseo personal.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La ampliaci\u00f3n del\u00a0Working\u00a0Families\u00a0Tax\u00a0Credit\u00a0(cr\u00e9dito fiscal para las familias trabajadoras).\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una desgravaci\u00f3n fiscal hist\u00f3rica para los negocios peque\u00f1os de nuestro estado.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Garantizar desayunos y almuerzos escolares gratuitos para todos los estudiantes de Washington.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Destinar el 5\u202f% de los ingresos a programas de atenci\u00f3n infantil y de educaci\u00f3n temprana.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-19-1024x683.jpg\" alt=\"\" class=\"wp-image-30334\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-19-1024x683.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-19-300x200.jpg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-19-768x512.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-19-1536x1024.jpg 1536w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-19-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"promote-economic-justice\">Nuestro objetivo: Promover la justicia econ\u00f3mica, la asequibilidad y las protecciones para las personas trabajadoras<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Justicia para los inmigrantes<\/strong>: Hemos conseguido protecciones para los trabajadores que son inmigrantes al\u00a0<strong>exigirles a los empleadores que les notifiquen a los trabajadores sobre las auditor\u00edas I-9 y al limitar el intercambio voluntario de sus datos con el DHS y ICE sin una orden judicial o una citaci\u00f3n.<\/strong>\u00a0Tambi\u00e9n conseguimos\u00a0<strong>que se les prohibiera a los agentes de los cuerpos oficiales, incluidos los agentes de ICE y los agentes federales, cubrirse el rostro de forma ilegal.<\/strong>\u00a0Nuestras comunidades son menos seguras cuando hay personas enmascaradas que se llevan a nuestros vecinos, y esta nueva ley tiene como prop\u00f3sito garantizar que nadie pueda ocultar su identidad mientras lleva a cabo actividades policiales, con el fin de asegurar la rendici\u00f3n de cuentas y la transparencia ante cualquier violaci\u00f3n de los derechos civiles.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Los derechos de los trabajadores<\/strong>: Tras a\u00f1os de lucha por esta causa, se aprob\u00f3 la carta de derechos de los\u00a0domestic\u00a0workers\u00a0(trabajadores dom\u00e9sticos), que trajo protecciones laborales esenciales para ni\u00f1eras, personal de limpieza del hogar, jardineros y otros\u00a0domestic\u00a0workers\u00a0(trabajadores dom\u00e9sticos), incluidas un salario m\u00ednimo, el derecho a conservar la identificaci\u00f3n y los documentos personales, protecci\u00f3n contra la discriminaci\u00f3n y las herramientas para hacer valer estos derechos. Se trata de protecciones laborales b\u00e1sicas de las que los\u00a0domestic\u00a0workers\u00a0(trabajadores dom\u00e9sticos) han sido excluidos durante demasiado tiempo. Tambi\u00e9n se aprob\u00f3 la ley de activaci\u00f3n de la Junta Nacional de Relaciones Laborales (NLRB), que proteger\u00eda los derechos de negociaci\u00f3n colectiva y las garant\u00edas de los trabajadores en caso de que la NLRB ya no los cubriera.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Hacer que los servicios p\u00fablicos sean asequibles<\/strong>: Hemos aprobado el proyecto de ley\u202f1903 de la House (C\u00e1mara), que establece un nuevo programa de servicios p\u00fablicos que ofrecer\u00e1 descuentos y bonificaciones mensuales en las facturas de servicios p\u00fablicos para ayudar a hacerle frente al aumento de los costos de energ\u00eda. Tambi\u00e9n hemos ampliado el\u00a0State\u00a0Home Energy\u00a0Assistance\u00a0Program\u00a0(Programa Estatal de Ayuda con el Servicio de Energ\u00eda para Viviendas), casi duplicando su alcance, lo que permitir\u00e1 que m\u00e1s grupos familiares reciban ayudas con el servicio de energ\u00eda para el pago de facturas de calefacci\u00f3n y aire acondicionado.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Luchar por vivienda segura y asequible<\/strong>: En el presupuesto se incluyeron inversiones hist\u00f3ricas de $200\u202fmillones destinadas a la construcci\u00f3n de viviendas\u00a0asequibles, junto con medidas para reducir las barreras a su construcci\u00f3n y aumentar los recursos y la flexibilidad de financiaci\u00f3n para proyectos de viviendas asequibles y para personas con bajos ingresos.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ampliar el\u00a0Working\u00a0Families\u00a0Tax\u00a0Credit\u00a0(cr\u00e9dito fiscal para las familias trabajadoras) para m\u00e1s de 1.3\u202fmillones de habitantes de Washington<\/strong>: Financiado en parte con el dinero recaudado a trav\u00e9s del impuesto a los millonarios, este cr\u00e9dito fiscal estar\u00e1 ahora disponible para las personas mayores de 18\u202fa\u00f1os (se ha ampliado, ya que antes solo cubr\u00eda a personas de entre 25 y 65\u202fa\u00f1os) y eleva el l\u00edmite de ingresos para acceder a \u00e9l, lo que significa que la devoluci\u00f3n de impuestos estar\u00e1 disponible para muchas m\u00e1s personas que necesitan este apoyo econ\u00f3mico.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Promover la seguridad p\u00fablica y comunitaria<\/strong>: Se garantiza la seguridad de nuestras comunidades al permitir que el fiscal general investigue las faltas graves de las fuerzas de los agentes de los cuerpos oficiales, limite el intercambio de datos de los lectores autom\u00e1ticos de matr\u00edculas y aumente los requisitos de elegibilidad para los alguaciles y jefes de polic\u00eda elegidos.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Por lo que seguimos luchando&nbsp;&nbsp;<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ampliaci\u00f3n de Apple\u00a0Health<\/strong>: Se pueden a\u00f1adir 5,000\u202fpersonas m\u00e1s al programa de ampliaci\u00f3n de Apple\u00a0Health, pero esto sigue dejando a decenas de miles de inmigrantes sin acceso a los programas de atenci\u00f3n m\u00e9dica simplemente por el lugar donde nacieron. Seguiremos luchando para que todas las personas que necesitan atenci\u00f3n m\u00e9dica est\u00e9n cubiertas.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inversiones obligatorias en la fuerza laboral de\u00a0nursing\u00a0homes\u00a0(asilos para ancianos)<\/strong>: Seguiremos presionando a los legisladores para que responsabilicen a las empresas de\u00a0nursing\u00a0homes\u00a0(asilos para ancianos). Necesitamos una pol\u00edtica que garantice que al menos el 60\u202f% de los ingresos se destine a los salarios y beneficios de los trabajadores que brindan cuidado y apoyo a los residentes, y no a los directores generales y ejecutivos de los\u00a0nursing\u00a0homes\u00a0(asilos para ancianos) que se benefician de nuestro arduo trabajo.\u00a0\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tarifas de servicios de vida con apoyo y transparencia salarial<\/strong>: Los profesionales de servicios de vida con apoyo merecen transparencia\u00a0en relaci\u00f3n a\u00a0c\u00f3mo los aumentos salariales que conseguimos en la legislatura se traducen en los salarios y beneficios que nos corresponden.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Pagar a los padres de ni\u00f1os con\u00a0developmental\u00a0disabilities\u00a0(discapacidades del desarrollo)<\/strong>: Actualmente, solo los padres de ni\u00f1os mayores de 18\u202fa\u00f1os pueden ser cuidadores remunerados de nuestros ni\u00f1os elegibles para recibir los servicios de Medicaid. La legislatura debe corregir esta notoria injusticia permitiendo que los padres de ni\u00f1os menores de 18\u202fa\u00f1os elegibles para recibir los servicios de Medicaid sean cuidadores remunerados.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Permitir que los c\u00f3nyuges brinden atenci\u00f3n remunerada a los seres queridos<\/strong>: Necesitamos un cambio en la ley para permitir que los c\u00f3nyuges reciban capacitaci\u00f3n y un pago por el servicio de cuidados y apoyo que ya brindan a sus seres queridos.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-7-1024x683.jpg\" alt=\"\" class=\"wp-image-30340\" style=\"aspect-ratio:1.4992905143101924;width:768px;height:auto\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-7-1024x683.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-7-300x200.jpg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-7-768x512.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-7-1536x1024.jpg 1536w, https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/01-21-2026-Purple-Presence-1-7-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los cuidadores no dimos marcha atr\u00e1s en ning\u00fan momento durante la sesi\u00f3n legislativa de Washington 2026.&nbsp;Nos enfrentamos a grandes dificultades y amenazas de recortes devastadores a la atenci\u00f3n a largo plazo, pero nos manifestamos con fuerza.&nbsp;Llevamos a cabo congregaciones en Olympia, Spokane, Yakima y Bellingham; vestimos al Capitolio de morado durante tres&nbsp;Purple&nbsp;Presences; y alzamos la [&hellip;]<\/p>\n","protected":false},"author":5669,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-29869","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agenda legislativa de Washington para el 2026 - SEIU 775<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/es\/2026waleg\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda legislativa de Washington para el 2026 - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Los cuidadores no dimos marcha atr\u00e1s en ning\u00fan momento durante la sesi\u00f3n legislativa de Washington 2026.&nbsp;Nos enfrentamos a grandes dificultades y amenazas de recortes devastadores a la atenci\u00f3n a largo plazo, pero nos manifestamos con fuerza.&nbsp;Llevamos a cabo congregaciones en Olympia, Spokane, Yakima y Bellingham; vestimos al Capitolio de morado durante tres&nbsp;Purple&nbsp;Presences; y alzamos la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/es\/2026waleg\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T17:29:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2026waleg\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2026waleg\\\/\",\"name\":\"Agenda legislativa de Washington para el 2026 - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2026waleg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2026waleg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC01688-2-1024x683.jpg\",\"datePublished\":\"2025-12-22T18:47:42+00:00\",\"dateModified\":\"2026-03-27T17:29:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2026waleg\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/es\\\/2026waleg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2026waleg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC01688-2-1024x683.jpg\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/DSC01688-2-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2026waleg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda legislativa de Washington para el 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenda legislativa de Washington para el 2026 - SEIU 775","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/es\/2026waleg\/","og_locale":"es_ES","og_type":"article","og_title":"Agenda legislativa de Washington para el 2026 - SEIU 775","og_description":"Los cuidadores no dimos marcha atr\u00e1s en ning\u00fan momento durante la sesi\u00f3n legislativa de Washington 2026.&nbsp;Nos enfrentamos a grandes dificultades y amenazas de recortes devastadores a la atenci\u00f3n a largo plazo, pero nos manifestamos con fuerza.&nbsp;Llevamos a cabo congregaciones en Olympia, Spokane, Yakima y Bellingham; vestimos al Capitolio de morado durante tres&nbsp;Purple&nbsp;Presences; y alzamos la [&hellip;]","og_url":"https:\/\/seiu775.org\/es\/2026waleg\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2026-03-27T17:29:07+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/es\/2026waleg\/","url":"https:\/\/seiu775.org\/es\/2026waleg\/","name":"Agenda legislativa de Washington para el 2026 - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seiu775.org\/es\/2026waleg\/#primaryimage"},"image":{"@id":"https:\/\/seiu775.org\/es\/2026waleg\/#primaryimage"},"thumbnailUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-1024x683.jpg","datePublished":"2025-12-22T18:47:42+00:00","dateModified":"2026-03-27T17:29:07+00:00","breadcrumb":{"@id":"https:\/\/seiu775.org\/es\/2026waleg\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/es\/2026waleg\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/es\/2026waleg\/#primaryimage","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-1024x683.jpg","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2026\/03\/DSC01688-2-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/es\/2026waleg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"Agenda legislativa de Washington para el 2026"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/29869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/5669"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=29869"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/29869\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=29869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":29609,"date":"2025-11-10T09:04:27","date_gmt":"2025-11-10T17:04:27","guid":{"rendered":"https:\/\/seiu775.org\/recursos-de-asistencia-alimentaria\/"},"modified":"2025-12-10T15:15:45","modified_gmt":"2025-12-10T23:15:45","slug":"food-assistance-resources","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/food-assistance-resources\/","title":{"rendered":"Recursos de asistencia alimentaria&nbsp;"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Encontrar apoyo<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Verifique si los bancos de alimentos, las iglesias y las organizaciones comunitarias locales est\u00e1n realizando colectas de alimentos.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Washington:<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.efoodnet.org\/find-food\/\">Find Food \u2013 Emergency Food Network<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.hungerfreewa.org\/foodbanks\"><strong>Encontrar un banco de alimentos \u2014 Hunger Free Washington<\/strong><\/a> (<em>Este recurso tambi\u00e9n est\u00e1 disponible en espa\u00f1ol, vietnamita, ruso, ucraniano, tagalo, somal\u00ed, coreano, \u00e1rabe, chino simplificado y jemer<\/em>).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Montana:<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/mfbn.org\/get-help\/\" target=\"_blank\" rel=\"noreferrer noopener\">Encontrar un banco de alimentos y conectarse con otros servicios<\/a>&nbsp;<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Alaska: <\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/foodbankofalaska.org\/agency-partners\"><strong>Encontrar un banco de alimentos&nbsp;<\/strong>&nbsp;<\/a><\/p>\n\n\n\n<ul class=\"wp-block-list\"><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Otros recursos<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni\u00f3n lucha por salvar Medicaid<\/a>&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Recursos para la defensa en materia de inmigraci\u00f3n<\/a>&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encontrar apoyo&nbsp; Verifique si los bancos de alimentos, las iglesias y las organizaciones comunitarias locales est\u00e1n realizando colectas de alimentos.&nbsp; Washington: Find Food \u2013 Emergency Food Network Encontrar un banco de alimentos \u2014 Hunger Free Washington (Este recurso tambi\u00e9n est\u00e1 disponible en espa\u00f1ol, vietnamita, ruso, ucraniano, tagalo, somal\u00ed, coreano, \u00e1rabe, chino simplificado y jemer). Montana: [&hellip;]<\/p>\n","protected":false},"author":5669,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-29609","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recursos de asistencia alimentaria&nbsp; - SEIU 775<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/es\/food-assistance-resources\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recursos de asistencia alimentaria&nbsp; - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Encontrar apoyo&nbsp; Verifique si los bancos de alimentos, las iglesias y las organizaciones comunitarias locales est\u00e1n realizando colectas de alimentos.&nbsp; Washington: Find Food \u2013 Emergency Food Network Encontrar un banco de alimentos \u2014 Hunger Free Washington (Este recurso tambi\u00e9n est\u00e1 disponible en espa\u00f1ol, vietnamita, ruso, ucraniano, tagalo, somal\u00ed, coreano, \u00e1rabe, chino simplificado y jemer). Montana: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/es\/food-assistance-resources\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T23:15:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/food-assistance-resources\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/es\\\/food-assistance-resources\\\/\",\"name\":\"Recursos de asistencia alimentaria&nbsp; - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"datePublished\":\"2025-11-10T17:04:27+00:00\",\"dateModified\":\"2025-12-10T23:15:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/food-assistance-resources\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/es\\\/food-assistance-resources\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/food-assistance-resources\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recursos de asistencia alimentaria&nbsp;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recursos de asistencia alimentaria&nbsp; - SEIU 775","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/es\/food-assistance-resources\/","og_locale":"es_ES","og_type":"article","og_title":"Recursos de asistencia alimentaria&nbsp; - SEIU 775","og_description":"Encontrar apoyo&nbsp; Verifique si los bancos de alimentos, las iglesias y las organizaciones comunitarias locales est\u00e1n realizando colectas de alimentos.&nbsp; Washington: Find Food \u2013 Emergency Food Network Encontrar un banco de alimentos \u2014 Hunger Free Washington (Este recurso tambi\u00e9n est\u00e1 disponible en espa\u00f1ol, vietnamita, ruso, ucraniano, tagalo, somal\u00ed, coreano, \u00e1rabe, chino simplificado y jemer). Montana: [&hellip;]","og_url":"https:\/\/seiu775.org\/es\/food-assistance-resources\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2025-12-10T23:15:45+00:00","twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/es\/food-assistance-resources\/","url":"https:\/\/seiu775.org\/es\/food-assistance-resources\/","name":"Recursos de asistencia alimentaria&nbsp; - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"datePublished":"2025-11-10T17:04:27+00:00","dateModified":"2025-12-10T23:15:45+00:00","breadcrumb":{"@id":"https:\/\/seiu775.org\/es\/food-assistance-resources\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/es\/food-assistance-resources\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/es\/food-assistance-resources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"Recursos de asistencia alimentaria&nbsp;"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/29609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/5669"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=29609"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/29609\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=29609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":27972,"date":"2025-05-29T14:29:12","date_gmt":"2025-05-29T21:29:12","guid":{"rendered":"https:\/\/seiu775.org\/medicaid-federal-actualizaciones-acciones-y-eventos-para-mantenerse-informado-mientras-nuestra-unin-lucha-por-salvar-medicaid\/"},"modified":"2025-07-23T13:47:58","modified_gmt":"2025-07-23T20:47:58","slug":"federal-medicaid-stay-informed-es","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/","title":{"rendered":"Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Los republicanos de la House of Representatives (C\u00e1mara de Representantes) han votado a favor de aprobar los mayores recortes a Medicaid en la historia de los Estados Unidos, con un recorte de $715.000\u00a0millones que dejar\u00eda sin atenci\u00f3n m\u00e9dica a 13.7\u00a0millones de personas.\u00a0<\/strong>\u00a0\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Si bien nuestros clientes se salvaron de lo peor de los recortes propuestos, quienes dependen de Medicaid para su propia atenci\u00f3n m\u00e9dica, incluidos muchos cuidadores de Montana y Alaska, y muchos de nuestros amigos y familiares, se ver\u00e1n afectados por este plan en caso de que el Congreso lo apruebe. Si usted est\u00e1 en Washington y recibe su seguro m\u00e9dico de nuestra Uni\u00f3n, dicho seguro m\u00e9dico se mantendr\u00e1. <strong>Sin embargo, si usted o las personas que conoce reciben atenci\u00f3n m\u00e9dica a trav\u00e9s de Medicaid o Apple Health, como se le conoce mejor en Washington, debe saber que los republicanos en el Congreso est\u00e1n tratando de quit\u00e1rselo.\u00a0\u00a0\u00a0<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Ahora le corresponde al Senado redactar y votar su versi\u00f3n del presupuesto. Por eso es a\u00fan m\u00e1s importante alzar la voz y dejar claro que no nos quedaremos callados mientras los pol\u00edticos intentan eliminar a Medicaid. Haremos m\u00e1s ruido, seremos m\u00e1s fuertes y no dejaremos de luchar.\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Nuestra Uni\u00f3n no dejar\u00e1 de luchar contra estos recortes. A medida que crece la amenaza de recortes a Medicaid, tambi\u00e9n lo hace nuestra lucha por salvarlo. <strong>Obtenga m\u00e1s informaci\u00f3n de parte de Sterling Harders, nuestra presidenta de SEIU\u00a0775, sobre lo que nuestra Uni\u00f3n est\u00e1 haciendo para tomar medidas que protejan a Medicaid<\/strong>.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/youtu.be\/etWGwOnkPis?si=PRCEVZwgKEIHmoMk\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3-1024x1024.jpg\" alt=\"\" class=\"wp-image-27696\" style=\"width:417px;height:auto\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3-1024x1024.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3-300x300.jpg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3-150x150.jpg 150w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3-768x768.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">  <a href=\"https:\/\/seiu775.org\/es\/tth\/\">Escuche el foro comunitario telef\u00f3nico en varios idiomas aqu\u00ed.<\/a><\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Usted puede decirle al Congress (Congreso) NO a los recortes a Medicaid:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/speak4.app\/lp\/kk01fs0b\">Enviando un correo electr\u00f3nico al Congress (Congreso).<\/a><\/li>\n\n\n\n<li><strong>Llamando a sus miembros del Congress (Congreso) a esta l\u00ednea gratuita: 866-426-2631 y haci\u00e9ndoles saber que necesitamos proteger a Medicaid.<\/strong><\/li>\n\n\n\n<li><a href=\"https:\/\/seiu775.org\/es\/login\/\">Iniciando sesi\u00f3n en nuestro sitio web para saber si habr\u00e1 un evento o congregaci\u00f3n cerca de usted.<\/a><\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>LO QUE EST\u00c1 HACIENDO NUESTRA UNI\u00d3N<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Cuando nuestros trabajos y la atenci\u00f3n de los clientes se ven amenazados, <strong>nuestra Uni\u00f3n toma medidas.<\/strong> Los cuidadores de Washington, Montana y Alaska est\u00e1n alzando la voz para proteger a Medicaid.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>WASHINGTON D.C.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">15\u00a0cuidadores de SEIU\u00a0775 de Washington, Montana y Alaska viajaron a Washington, D.C. para manifestarse a favor de Medicaid y reunirse con miembros del Congress (Congreso) en torno a la importancia de proteger estos programas vitales.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/04\/DSC00691-1-2-683x1024.jpg\" alt=\"\" class=\"wp-image-27763\" style=\"width:337px;height:auto\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/04\/DSC00691-1-2-683x1024.jpg 683w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/04\/DSC00691-1-2-200x300.jpg 200w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/04\/DSC00691-1-2-768x1152.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/04\/DSC00691-1-2-1024x1536.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/04\/DSC00691-1-2-1365x2048.jpg 1365w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/04\/DSC00691-1-2-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\"><strong>WASHINGTON<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">En Washington, los cuidadores han estado defendiendo ante los miembros del Congress (Congreso) la importancia de la financiaci\u00f3n de Medicaid para sus clientes.<\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Alyssa O., una IP y AP de Sedro Woolley, Washington, habl\u00f3 recientemente con el representante Rick Larsen en una mesa redonda sobre c\u00f3mo Medicaid cubre la atenci\u00f3n necesaria y la atenci\u00f3n por parte de m\u00e9dicos especializados de sus clientes. El representante Larsen se reuni\u00f3 posteriormente con Alyssa y le pidi\u00f3 que compartiera m\u00e1s informaci\u00f3n sobre el impacto: <a href=\"https:\/\/youtu.be\/QybL6MX6gcs\">puede ver el video aqu\u00ed.<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Nelly P., una IP de Sunnyside, Washington, se uni\u00f3 a los trabajadores de atenci\u00f3n m\u00e9dica del centro y este de Washington en una conferencia de prensa con la senadora Patty Murray para hacer sonar las alarmas respecto a los recortes a Medicaid que se avecinan.<\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>\u201cEstoy muy molesta por los posibles recortes a Medicaid; \u00bfqu\u00e9 pasa con los clientes que dependen de la financiaci\u00f3n de Medicaid para recibir atenci\u00f3n? \u00bfQu\u00e9 va a pasar con ellos? \u00bfDe d\u00f3nde obtendr\u00e1n el dinero para los tratamientos que salvan vidas? Los legisladores republicanos no ven a qui\u00e9n est\u00e1n afectando ni qu\u00e9 est\u00e1n haciendo\u201d.<br\/><strong>\u2013 Nelly P. (IP, Sunnyside, Washington)<\/strong><br\/><a href=\"https:\/\/youtu.be\/Bv7E_P8JLaI?si=fLEFSNU3uNnf18Ov&amp;t=777\">Aqu\u00ed puede ver a Nelly hablar con la senadora Patty Murray en la conferencia de prensa.<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>MONTANA<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">En Montana, estamos celebrando haber salvado y obtenido la expansi\u00f3n de Medicaid a nivel estatal, lo que significa que ahora estamos poniendo toda nuestra atenci\u00f3n en salvar Medicaid a nivel federal.<\/p>\n\n<p class=\"wp-block-paragraph\">Los cuidadores de Montana lucharon por primera vez para aprobar la expansi\u00f3n de Medicaid en 2015, y la defendieron con \u00e9xito en 2025 con la aprobaci\u00f3n del proyecto de ley HB\u00a0245, que elimin\u00f3 la cl\u00e1usula de caducidad. En febrero, se aprob\u00f3 en el Senate (Senado) con 29\u00a0votos a favor y 21 en contra, una victoria significativa. En conjunto, los cuidadores dejaron 300\u00a0mensajes instando a los legisladores a votar \u201cs\u00ed\u201d.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>ALASKA<\/strong><\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/DSC00472-1-1024x683.jpg\" alt=\"\" class=\"wp-image-27690\" style=\"width:405px;height:auto\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/DSC00472-1-1024x683.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/DSC00472-1-300x200.jpg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/DSC00472-1-768x512.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/DSC00472-1-1536x1024.jpg 1536w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/DSC00472-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Los cuidadores y miembros de la comunidad de Alaska se congregaron en el Capitolio estatal de Juneau para pedirle al congreso de Alaska que defendiera Medicaid. <a href=\"https:\/\/www.juneauempire.com\/news\/alaskans-across-the-state-rally-to-save-medicaid-their-lifeline\/\">Puede leer m\u00e1s sobre esta congregaci\u00f3n aqu\u00ed.<\/a><br\/>El 20 de febrero, los cuidadores se reunieron frente a las oficinas de los senadores Murkowski y Sullivan para manifestarse contra los recortes a Medicaid. Kim A., una cuidadora de Anchorage, Alaska, habl\u00f3 sobre sus clientes que dependen de Medicaid para recibir atenci\u00f3n esencial que salva vidas. <a href=\"https:\/\/www.adn.com\/alaska-news\/2025\/02\/26\/alaskans-say-medicaid-cuts-considered-by-us-house-could-be-catastrophic\/\">Adem\u00e1s de participar en la congregaci\u00f3n, Kim tambi\u00e9n viaj\u00f3 a Washington, D.C., para defender a sus clientes y a los habitantes de Alaska que dependen de Medicaid.<\/a> <a href=\"https:\/\/www.facebook.com\/protectourcareAK\/videos\/1031840898847394\">Vea aqu\u00ed el discurso de Kim durante la congregaci\u00f3n.<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Tambi\u00e9n estamos haciendo que nuestros miembros del Congress (Congreso) rindan cuentas. La cuidadora Essie F., de Fairbanks, Alaska, viaj\u00f3 a Washington, D.C. en diciembre y habl\u00f3 con el representante Nick Begich III. \u201cElla afirm\u00f3 que Begich la recibi\u00f3 muy bien. \u2018\u00c9l asegur\u00f3 que nos apoyaba al 100\u00a0% en la lucha para evitar cualquier recorte a Medicaid\u2019, dijo Frank. Ahora, ella dice sentirse traicionada por su voto\u201d.<a href=\"https:\/\/www.adn.com\/alaska-news\/2025\/02\/26\/alaskans-say-medicaid-cuts-considered-by-us-house-could-be-catastrophic\/\"> Aqu\u00ed puede leer el art\u00edculo completo en el que ella comparte esto con otros nativos de Alaska.<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los republicanos de la House of Representatives (C\u00e1mara de Representantes) han votado a favor de aprobar los mayores recortes a Medicaid en la historia de los Estados Unidos, con un recorte de $715.000\u00a0millones que dejar\u00eda sin atenci\u00f3n m\u00e9dica a 13.7\u00a0millones de personas.\u00a0\u00a0\u00a0 Si bien nuestros clientes se salvaron de lo peor de los recortes propuestos, [&hellip;]<\/p>\n","protected":false},"author":1700,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-27972","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid - SEIU 775<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Los republicanos de la House of Representatives (C\u00e1mara de Representantes) han votado a favor de aprobar los mayores recortes a Medicaid en la historia de los Estados Unidos, con un recorte de $715.000\u00a0millones que dejar\u00eda sin atenci\u00f3n m\u00e9dica a 13.7\u00a0millones de personas.\u00a0\u00a0\u00a0 Si bien nuestros clientes se salvaron de lo peor de los recortes propuestos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T20:47:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/federal-medicaid-stay-informed-es\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/es\\\/federal-medicaid-stay-informed-es\\\/\",\"name\":\"Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/federal-medicaid-stay-informed-es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/federal-medicaid-stay-informed-es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Teletown-Hall-March-2025-3-1024x1024.jpg\",\"datePublished\":\"2025-05-29T21:29:12+00:00\",\"dateModified\":\"2025-07-23T20:47:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/federal-medicaid-stay-informed-es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/es\\\/federal-medicaid-stay-informed-es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/federal-medicaid-stay-informed-es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Teletown-Hall-March-2025-3-1024x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Teletown-Hall-March-2025-3-1024x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/federal-medicaid-stay-informed-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid - SEIU 775","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/","og_locale":"es_ES","og_type":"article","og_title":"Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid - SEIU 775","og_description":"Los republicanos de la House of Representatives (C\u00e1mara de Representantes) han votado a favor de aprobar los mayores recortes a Medicaid en la historia de los Estados Unidos, con un recorte de $715.000\u00a0millones que dejar\u00eda sin atenci\u00f3n m\u00e9dica a 13.7\u00a0millones de personas.\u00a0\u00a0\u00a0 Si bien nuestros clientes se salvaron de lo peor de los recortes propuestos, [&hellip;]","og_url":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2025-07-23T20:47:58+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/","url":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/","name":"Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/#primaryimage"},"image":{"@id":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/#primaryimage"},"thumbnailUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3-1024x1024.jpg","datePublished":"2025-05-29T21:29:12+00:00","dateModified":"2025-07-23T20:47:58+00:00","breadcrumb":{"@id":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/#primaryimage","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3-1024x1024.jpg","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/03\/Teletown-Hall-March-2025-3-1024x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/es\/federal-medicaid-stay-informed-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"Medicaid federal: Actualizaciones, acciones y eventos para mantenerse informado mientras nuestra Uni&oacute;n lucha por salvar Medicaid"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/27972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/1700"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=27972"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/27972\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=27972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":27616,"date":"2025-03-10T07:57:50","date_gmt":"2025-03-10T14:57:50","guid":{"rendered":"https:\/\/seiu775.org\/recursos-para-la-defensa-en-materia-de-inmigracin\/"},"modified":"2026-08-28T15:59:43","modified_gmt":"2026-08-28T22:59:43","slug":"immigration-defense-resources-es","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/","title":{"rendered":"Recursos para la defensa en materia de inmigraci&oacute;n"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Una meta de nuestra Uni\u00f3n es luchar por la justicia para todos<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Como uni\u00f3n, apoyamos a TODOS nuestros miembros, incluyendo a aquellos que son inmigrantes o viven en familias de inmigrantes, as\u00ed como el impulso que compartimos de vivir nuestras vidas con dignidad y realizar nuestros trabajos con seguridad y protecci\u00f3n. Creemos que no hay justicia hasta que haya justicia para todos. Es por eso que la mayor\u00eda de nuestros miembros han expresado contundentemente que quieren que nuestra Uni\u00f3n defienda a los trabajadores inmigrantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"#care\" data-type=\"internal\" data-id=\"#care\">Recursos para la atenci\u00f3n<\/a><\/strong><br><strong><a href=\"#legal\">Obtenga ayuda legal relacionada con la inmigraci\u00f3n<\/a><br><a href=\"#rights\">Conozca sus derechos<\/a><br><a href=\"#organizations\">Organizaciones de confianza de derechos de los inmigrantes<\/a><br><a href=\"#safety\">Planes de seguridad y preparaci\u00f3n familiar ante emergencias<\/a><br><a href=\"#information\">Informaci\u00f3n adicional<\/a><br><a href=\"#involved\">Participe<\/a><\/strong><\/p>\n\n\n\n<h3 id=\"care\" class=\"wp-block-heading\"><strong>Recursos para la atenci\u00f3n<\/strong><strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El 1.\u00ba de octubre del 2026, m\u00e1s de 1,000&nbsp;adultos mayores y personas con discapacidad en Washington perder\u00e1n sus servicios de atenci\u00f3n a largo plazo, y 14,000&nbsp;inmigrantes de Washington perder\u00e1n su cobertura de atenci\u00f3n m\u00e9dica, debido a los crueles recortes a la atenci\u00f3n que contiene el HR&nbsp;1, el proyecto de ley \u201cBig Ugly\u201d de Trump. Las personas pierden los servicios de atenci\u00f3n simplemente por el lugar donde nacieron.&nbsp;<strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si su cliente se ve afectado por estos recortes, habr\u00e1 recibido una carta del DSHS en agosto inform\u00e1ndole sobre los cambios en su elegibilidad para Apple Health (Medicaid) y los servicios de atenci\u00f3n a largo plazo y conocer\u00e1 directamente de parte de su administrador del caso dicha situaci\u00f3n antes del 15 de septiembre del 2026.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/seiu775.org\/immigrant-care-cuts\/\">Haga clic aqu\u00ed para obtener informaci\u00f3n con respecto a si su cliente perder\u00e1 los servicios de atenci\u00f3n el 1.\u00ba de octubre<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le pedimos al gobernador Ferguson y a la legislatura estatal que reconozcan que se trata de una emergencia, y le pedimos el gobernador que utilice los fondos de emergencia para cubrir el vac\u00edo relacionado con la atenci\u00f3n a los inmigrantes.<\/strong>\u00a0Hemos conseguido avances anteriormente al hacernos escuchar.\u00a0Ahora, debemos hacerlo nuevamente.\u00a0<a href=\"https:\/\/actionnetwork.org\/letters\/immigrant-care-wa\/\">Firme nuestra petici\u00f3n para exigirle al gobernador Ferguson y a nuestros legisladores que act\u00faen.<\/a><\/p>\n\n\n\n<h3 id=\"legal\" class=\"wp-block-heading\">Obtenga ayuda legal relacionada con la inmigraci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los miembros de SEIU&nbsp;775 que tengan preguntas legales espec\u00edficas sobre la inmigraci\u00f3n pueden comunicarse con el Member Resource Center (Centro de Informaci\u00f3n para Miembros) al 1-866-371-3200, de lunes a viernes, de 8&nbsp;a.&nbsp;m. a 4:30&nbsp;p.&nbsp;m. (hora del Pac\u00edfico), o enviarnos un correo electr\u00f3nico a <a href=\"mailto:mrc@seiu775.org\" target=\"_blank\" rel=\"noreferrer noopener\">mrc@seiu775.org<\/a>.<\/p>\n\n\n\n<h3 id=\"rights\" class=\"wp-block-heading\">Conozca sus derechos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sin importar su estado migratorio, est\u00e1 protegido por la Constituci\u00f3n de los Estados Unidos. Conocer sus derechos puede mantenerlo seguro a usted y a su familia.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qu\u00e9 debe hacer si se encuentra con Immigration Customs and Enforcement (ICE):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>NO ABRA LA PUERTA <\/strong>Si un agente de inmigraci\u00f3n llega a su puerta, mantenga la calma y no abra la puerta. P\u00eddale que deslice cualquier documento por debajo de la puerta o que lo muestre a trav\u00e9s de una ventana.<\/li>\n\n\n\n<li><strong>NO LES PERMITA ENTRAR SIN UNA ORDEN JUDICIAL <\/strong>Los agentes de inmigraci\u00f3n no pueden entrar a su hogar sin una orden firmada por un juez.<\/li>\n\n\n\n<li><strong>DET\u00c9NGASE DE MANERA SEGURA Y MANTENGA LA CALMA<\/strong> Si lo detienen mientras conduce, det\u00e9ngase tan pronto como sea seguro hacerlo. Mantenga la calma y coopere.<\/li>\n\n\n\n<li><strong>PROPORCIONE LOS DOCUMENTOS CUANDO SE LO PIDAN<\/strong> Muestre su licencia de conducir, registro del autom\u00f3vil y prueba de seguro si se lo solicitan. Todav\u00eda tiene el derecho de guardar silencio sobre cualquier otra cosa.<\/li>\n\n\n\n<li><strong>PERMANEZCA EN SILENCIO <\/strong>No responda preguntas. Tiene el derecho de permanecer en silencio (5.\u00aa&nbsp;Enmienda). Simplemente diga: \u201cEjercer\u00e9 mi derecho de la 5.\u00aa&nbsp;Enmienda a permanecer en silencio\u201d.<\/li>\n\n\n\n<li><strong>TIENE EL DERECHO DE HABLAR CON UN ABOGADO <\/strong>No firme nada ni responda ninguna pregunta hasta que haya hablado con un abogado. El ICE puede usar todo lo que usted diga en su contra.<\/li>\n\n\n\n<li><strong>MANTENGA LOS DOCUMENTOS IMPORTANTES A MANO<\/strong> Haga copias de sus documentos de inmigraci\u00f3n e identificaci\u00f3n, y gu\u00e1rdelos de manera segura (DACA, permiso de trabajo, visa, tarjeta de residente permanente).<\/li>\n\n\n\n<li><strong>NO MIENTA NI PROPORCIONE DOCUMENTOS FALSOS<\/strong> Sea honesto y no entregue identificaciones o documentos falsos. Es un delito proporcionar documentos falsos.<\/li>\n<\/ul>\n\n\n\n<h3 id=\"organizations\" class=\"wp-block-heading\">Organizaciones de confianza de derechos de los inmigrantes<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><a href=\"https:\/\/iamerica.org\/know-your-rights\/\" target=\"_blank\" rel=\"noreferrer noopener\">iAmerica<\/a><\/mark><\/strong><a href=\"https:\/\/iamerica.org\/know-your-rights\/\">:<\/a> iAmerica es la plataforma nacional de campa\u00f1a por la justicia para inmigrantes de Service Employees International Union (SEIU). Estamos impulsando sue\u00f1os y promoviendo el cambio al defender los derechos de todas las familias estadounidenses. Informaci\u00f3n disponible en 21&nbsp;idiomas. <a href=\"https:\/\/iamerica.org\/know-your-rights\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Know Your Rights (Conozca sus derechos) &#8211; iAmerica<\/strong><\/a><\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><a href=\"https:\/\/www.aclu.org\/we-have-rights#:~:text=We%20Have%20Rights%20is%20a,immigrant%20justice%20in%20our%20country\" target=\"_blank\" rel=\"noreferrer noopener\">American Civil Liberties Union (ACLU):<\/a><\/mark><\/strong> Contiene una serie de videos llamada We Have Rights (Tenemos derechos) disponible en ingl\u00e9s, espa\u00f1ol, urdu, \u00e1rabe, criollo haitiano, ruso y mandar\u00edn. <a href=\"https:\/\/www.aclu.org\/we-have-rights#:~:text=We%20Have%20Rights%20is%20a,immigrant%20justice%20in%20our%20country\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>We Have Rights (Tenemos derechos) | American Civil Liberties Union<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.nwirp.org\/resources\/kyr\/\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\">Northwest Immigrant Rights Project (NWIRP):<\/mark><\/strong> <\/a>Northwest Immigrant Rights Project fomenta la justicia defendiendo y promoviendo los derechos de los inmigrantes a trav\u00e9s de servicios legales directos, defensa sist\u00e9mica y educaci\u00f3n comunitaria. <a href=\"https:\/\/www.nwirp.org\/resources\/kyr\/\"><strong>Know Your Rights (Conozca sus derechos) | <\/strong><\/a><a href=\"https:\/\/www.nwirp.org\/resources\/kyr\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>NWIRP<\/strong><\/a><a href=\"https:\/\/www.nwirp.org\/resources\/kyr\/\"><strong>.org<\/strong><\/a><\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><a href=\"https:\/\/weareoneamerica.org\/\">OneAmerica<\/a>:<\/mark><\/strong> Desarrolla liderazgo y organiza a l\u00edderes y aliados de bases en \u00e1reas claves en el estado de Washington para impulsar cambios de pol\u00edticas, movilizar la participaci\u00f3n c\u00edvica en las comunidades y abogar por sistemas que les den la bienvenida e incluyan inmigrantes en todos los niveles. <a href=\"https:\/\/weareoneamerica.org\/\"><strong>Home (Inicio) <\/strong>| <strong>OneAmerica<\/strong><\/a><\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><a href=\"https:\/\/waisn.org\/kyrice\/\" target=\"_blank\" rel=\"noreferrer noopener\">Washington Immigrant Solidarity Network (WAISN):<\/a><\/mark> <\/strong>WAISN es la coalici\u00f3n liderada por inmigrantes m\u00e1s grande de Washington, con m\u00e1s de 400&nbsp;organizaciones, incluidas organizaciones de inmigrantes y refugiados, uniones, grupos religiosos y organizaciones de base. Informaci\u00f3n disponible en ingl\u00e9s, espa\u00f1ol, franc\u00e9s, lingala, portugu\u00e9s y somal\u00ed.<strong> <a href=\"https:\/\/waisn.org\/kyrice\/\" target=\"_blank\" rel=\"noreferrer noopener\">Folleto Know Your Rights (Conozca sus derechos) ante el ICE &#8211; WAISN<\/a><\/strong><\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><a href=\"https:\/\/www.immigrantdefenseproject.org\/know-your-rights-with-ice\/\" target=\"_blank\" rel=\"noreferrer noopener\">The Immigrant Defense Project (IDP):<\/a><\/mark><\/strong> IDP fue fundada hace m\u00e1s de 20&nbsp;a\u00f1os para combatir una crisis emergente de derechos humanos: la persecuci\u00f3n de inmigrantes para su encarcelamiento masivo y deportaci\u00f3n. <a href=\"https:\/\/www.immigrantdefenseproject.org\/know-your-rights-with-ice\/\"><strong>Know Your Rights (Conozca sus derechos) ante el ICE &#8211; Immigrant Defense Project<\/strong><\/a><\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.cairwa.org\/\">CAIR Washington<\/a><\/strong> es una organizaci\u00f3n de defensor\u00eda y derechos civiles con sede en Seattle que ayuda a la comunidad musulmana en el estado de Washington. Su objetivo es defender las libertades civiles de los ciudadanos musulmanes de Washington, sin importar d\u00f3nde vivan o su nivel de ingresos. <a href=\"https:\/\/www.knowyourrightswa.com\/\"><strong>Know Your Rights (Conozca sus derechos) &#8211; CAIR Washington<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<h3 id=\"safety\" class=\"wp-block-heading\">Planes de seguridad y preparaci\u00f3n familiar ante emergencias<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"iAmerica: Make a Family Safety Plan - iAmerica\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><strong>iAmerica:<\/strong> <\/mark>Make a Family Safety Plan (Elabore un plan de seguridad para la familia) &#8211; iAmerica<\/a><\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><a href=\"https:\/\/www.cliniclegal.org\/epif\" target=\"_blank\" rel=\"noreferrer noopener\">CLINIC:<\/a><\/mark> <\/strong>Contiene una selecci\u00f3n de recursos nacionales y estatales para orientar a los inmigrantes, proveedores de servicios jur\u00eddicos y defensores cuando ayudan a las familias en riesgo de detenci\u00f3n o deportaci\u00f3n a planificar la protecci\u00f3n de sus familias y propiedades, y brindan preparaci\u00f3n ante emergencias para familias inmigrantes: <a href=\"https:\/\/www.cliniclegal.org\/epif\" target=\"_blank\" rel=\"noreferrer noopener\">A 50 State Resource (Un recurso para los 50&nbsp;estados) | Catholic Legal Immigration Network, Inc. (CLINIC)<\/a><\/li>\n<\/ul>\n\n\n\n<h3 id=\"information\" class=\"wp-block-heading\">Informaci\u00f3n adicional<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/waisn.org\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><strong>Washington Immigrant Solidarity Network<\/strong><\/mark><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\">(WAISN<\/mark><\/strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><strong>)<\/strong>:<\/mark> Informaci\u00f3n en 14&nbsp;idiomas.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.nwirp.org\/news-events\/events\/webinars\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-purple-color\"><strong>Northwest Immigrant Rights Project (NWIRP)<\/strong>:<\/mark> Seminarios web sobre diversos temas.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.atg.wa.gov\/immigration-services\"><strong>WA State Attorney General: <\/strong>Encuentre un abogado con licencia que se especialice en leyes migratorias<\/a>.<\/li>\n<\/ul>\n\n\n\n<h3 id=\"involved\" class=\"wp-block-heading\">Participe<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para participar y obtener m\u00e1s informaci\u00f3n, comun\u00edquese con el Member Resource Center (Centro de Informaci\u00f3n para Miembros, MRC) llamando al 1-866-371-3200 o enviando un correo electr\u00f3nico a mrc@seiu775.org entre las 8&nbsp;a.&nbsp;m. y las 4:30&nbsp;p.&nbsp;m. (hora del Pac\u00edfico), de lunes a viernes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/seiu775.org\/es\/food-assistance-resources\/\">Find additional resources for food assistance here. <\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una meta de nuestra Uni\u00f3n es luchar por la justicia para todos Como uni\u00f3n, apoyamos a TODOS nuestros miembros, incluyendo a aquellos que son inmigrantes o viven en familias de inmigrantes, as\u00ed como el impulso que compartimos de vivir nuestras vidas con dignidad y realizar nuestros trabajos con seguridad y protecci\u00f3n. Creemos que no hay [&hellip;]<\/p>\n","protected":false},"author":1700,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-27616","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recursos para la defensa en materia de inmigraci&oacute;n - SEIU 775<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recursos para la defensa en materia de inmigraci&oacute;n - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Una meta de nuestra Uni\u00f3n es luchar por la justicia para todos Como uni\u00f3n, apoyamos a TODOS nuestros miembros, incluyendo a aquellos que son inmigrantes o viven en familias de inmigrantes, as\u00ed como el impulso que compartimos de vivir nuestras vidas con dignidad y realizar nuestros trabajos con seguridad y protecci\u00f3n. Creemos que no hay [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T22:59:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/immigration-defense-resources-es\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/es\\\/immigration-defense-resources-es\\\/\",\"name\":\"Recursos para la defensa en materia de inmigraci&oacute;n - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"datePublished\":\"2025-03-10T14:57:50+00:00\",\"dateModified\":\"2026-08-28T22:59:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/immigration-defense-resources-es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/es\\\/immigration-defense-resources-es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/immigration-defense-resources-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recursos para la defensa en materia de inmigraci&oacute;n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recursos para la defensa en materia de inmigraci&oacute;n - SEIU 775","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/","og_locale":"es_ES","og_type":"article","og_title":"Recursos para la defensa en materia de inmigraci&oacute;n - SEIU 775","og_description":"Una meta de nuestra Uni\u00f3n es luchar por la justicia para todos Como uni\u00f3n, apoyamos a TODOS nuestros miembros, incluyendo a aquellos que son inmigrantes o viven en familias de inmigrantes, as\u00ed como el impulso que compartimos de vivir nuestras vidas con dignidad y realizar nuestros trabajos con seguridad y protecci\u00f3n. Creemos que no hay [&hellip;]","og_url":"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2026-08-28T22:59:43+00:00","twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/","url":"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/","name":"Recursos para la defensa en materia de inmigraci&oacute;n - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"datePublished":"2025-03-10T14:57:50+00:00","dateModified":"2026-08-28T22:59:43+00:00","breadcrumb":{"@id":"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/es\/immigration-defense-resources-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"Recursos para la defensa en materia de inmigraci&oacute;n"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/27616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/1700"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=27616"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/27616\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=27616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":27170,"date":"2025-01-06T14:18:22","date_gmt":"2025-01-06T22:18:22","guid":{"rendered":"https:\/\/seiu775.org\/?page_id=27170"},"modified":"2025-02-07T14:00:25","modified_gmt":"2025-02-07T22:00:25","slug":"2025waleg","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/2025waleg\/","title":{"rendered":"Agenda legislativa de Washington para el 2025"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Prioridades relacionadas con el progreso: Construir un futuro mejor para los cuidadores y las comunidades<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nuestra misi\u00f3n es unir las fuerzas de todos los cuidadores con el fin de mejorar nuestras vidas y las de aquellas personas bajo nuestro cuidado, as\u00ed como marcar el camino hacia un mundo m\u00e1s justo y equitativo. <\/strong>No somos un grupo de personas que se quedan de brazos cruzados. Nos tomamos el tiempo de pensar en d\u00f3nde estamos, a d\u00f3nde queremos ir y el trabajo que se necesita para lograrlo. Fijamos objetivos. Creamos planes. No le tememos a los cambios. Luchamos y hacemos posible lo que parece imposible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra misi\u00f3n, visi\u00f3n, valores y objetivos reflejan nuestros planes para el futuro y la forma en que establecemos nuestras prioridades.&nbsp; Nuestros objetivos son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Hacer del servicio de cuidados una profesi\u00f3n de calidad<\/strong><\/li>\n\n\n\n<li><strong>Ganar el acceso universal a la salud y atenci\u00f3n a largo plazo de calidad<\/strong><\/li>\n\n\n\n<li><strong>Luchar por la justicia para todos<\/strong><\/li>\n\n\n\n<li><strong>Empoderar a los cuidadores y dem\u00e1s trabajadores<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra agenda legislativa para el 2025 detalla lo que necesitamos ganar unidos durante la legislative session (sesi\u00f3n legislativa) de Washington para garantizar que el servicio de cuidados en Washington sea una profesi\u00f3n de calidad, proporcione cuidados de alta calidad a nuestros adultos mayores y a las personas con discapacidad, que todos los trabajadores puedan unirse para lograr cambios y que nuestras comunidades sean lugares de justicia e igualdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestras prioridades legislativas para el 2025 son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#FundHCR\">Financiar completamente la tarifa de atenci\u00f3n domiciliaria para los a\u00f1os 2025-2027 con el fin de garantizar salarios y beneficios justos para los cuidadores<\/a><\/li>\n\n\n\n<li><a href=\"#letuswork\">Agilizar el proceso de verificaci\u00f3n de antecedentes mediante la legislaci\u00f3n \u201cLet Us Work\u201d (D\u00e9jennos trabajar)<\/a> (HB 1395 | SB 5531)<\/li>\n\n\n\n<li><a href=\"#NHhealthcare\">Financiar el programa de atenci\u00f3n m\u00e9dica para essential workers (trabajadores indispensables) para proporcionar atenci\u00f3n m\u00e9dica asequible para los trabajadores de los nursing homes (asilos para ancianos)<\/a> (SB 5344 | HB 1523)<\/li>\n\n\n\n<li><a href=\"#WAcares\">Fortalecer nuestros beneficios p\u00fablicos de atenci\u00f3n a largo plazo de WA Cares<\/a> (SB 5291 | HB 1415)<\/li>\n\n\n\n<li><a href=\"#ParentProviders\">Pagar a los padres de ni\u00f1os con developmental disabilities (discapacidades del desarrollo)<\/a> (SB5211 | HB 1200)<\/li>\n\n\n\n<li><a href=\"#progressivetaxation\">Volver a nivelar nuestro c\u00f3digo fiscal para financiar los servicios esenciales y hacer que los ricos paguen la parte justa que les corresponde<\/a><\/li>\n\n\n\n<li><a href=\"#Rent-Stabilization\">Estabilizaci\u00f3n del alquiler, vivienda asequible y protecciones a los inquilinos<\/a> (HB 1217 | SB 5222)<\/li>\n\n\n\n<li><a href=\"#WFTC\">Ampliar el Working Families Tax Credit (cr\u00e9dito fiscal para las familias trabajadoras) para incluir a los j\u00f3venes adultos (de 18 a 24&nbsp;a\u00f1os) y a adultos mayores de m\u00e1s de 65&nbsp;a\u00f1os<\/a> (HB 1214)<\/li>\n\n\n\n<li><a href=\"#Unemployment-benefits\">Equidad de los beneficios de desempleo<\/a> (SB 5041 y SB 5026 | HB 1773)<\/li>\n\n\n\n<li><a href=\"#Police-accountability\">Rendici\u00f3n de cuentas de la polic\u00eda para mejorar la seguridad y la confianza de la comunidad<\/a><\/li>\n\n\n\n<li><a href=\"#Climate-justice\">Justicia clim\u00e1tica, incluyendo la ayuda con el servicio de energ\u00eda para las personas necesitadas<\/a><\/li>\n\n\n\n<li><a href=\"#PFML\">Aumentar el salario m\u00ednimo estatal a $25 la hora y garantizar las vacaciones pagadas y la licencia por duelo para todos los trabajadores<\/a> (SB 5578 | HB 1764)<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-27441\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-1024x576.jpeg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-300x169.jpeg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-768x432.jpeg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-1536x864.jpeg 1536w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-2048x1152.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"FundHCR\">Financiar completamente la tarifa de atenci\u00f3n domiciliaria para los a\u00f1os 2025-2027<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los cuidadores son el eje de nuestro sistema de atenci\u00f3n m\u00e9dica, brindan atenci\u00f3n esencial y compasiva a los adultos mayores y personas con discapacidad. Sin embargo, debido a la inflaci\u00f3n, nuestros sueldos no alcanzan para tanto como en el 2020, por lo que muchos cuidadores de Washington se enfrentan a la inestabilidad econ\u00f3mica. Al mismo tiempo, los clientes y las familias experimentan cada vez m\u00e1s escasez y retrasos en la atenci\u00f3n. Los cuidadores merecen salarios dignos y beneficios acordes con el costo de la vida. <strong>La financiaci\u00f3n completa de la tarifa de atenci\u00f3n domiciliaria para los a\u00f1os 2025-2027 es un paso fundamental para afrontar estos desaf\u00edos al:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Aumentar el salario inicial de los cuidadores a aproximadamente $23.70<\/strong>. Aunque propusimos restablecer los salarios al poder adquisitivo del 2020, los problemas presupuestarios significativos del estado hicieron que se tuviera que aceptar un restablecimiento del 50&nbsp;%.<\/li>\n\n\n\n<li><strong>Mejorar la cobertura de atenci\u00f3n m\u00e9dica<\/strong> al permitir que los cuidadores conserven la atenci\u00f3n m\u00e9dica asequible que cubra a los dependientes si han trabajado menos de las 80&nbsp;horas de forma temporal. Sin esta mejora, el 25&nbsp;% de los cuidadores continuar\u00e1n perdiendo cada a\u00f1o su atenci\u00f3n m\u00e9dica debido a la hospitalizaci\u00f3n del cliente, al fallecimiento del cliente u otros motivos que conlleven a la p\u00e9rdida de horas.<\/li>\n\n\n\n<li><strong>Obtener una mejora de los beneficios<\/strong> con modestos incrementos en la contribuci\u00f3n del empleador a los beneficios de jubilaci\u00f3n, algunos d\u00edas feriados adicionales y un leve aumento del reembolso de millas.<\/li>\n\n\n\n<li><strong>Financiaci\u00f3n de parity<\/strong> entre las agencias de atenci\u00f3n domiciliaria de Medicaid y un aumento importante de la tasa administrativa de CDE y los agency providers (proveedores de la agencia).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"letuswork\">Agilizar el proceso de verificaci\u00f3n de antecedentes mediante la legislaci\u00f3n \u201cLet Us Work\u201d (D\u00e9jennos trabajar) con una actualizaci\u00f3n t\u00e9cnica para garantizar un programa s\u00f3lido para los habitantes de Washington con necesidades.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>HB 1395 | SB 5531<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los cuidadores del estado de Washington se enfrentan a desaf\u00edos significativos como consecuencia del proceso de verificaci\u00f3n de antecedentes actual.<\/strong> Los abrumadores obst\u00e1culos administrativos con frecuencia ocasionan que los cuidadores pierdan salarios y beneficios e impiden que los cuidadores calificados empiecen o contin\u00faen brindando una atenci\u00f3n remunerada. Los problemas menores, como una sanci\u00f3n por arrojar basura o un cambio de nombre, requieren que el cuidador realice la revisi\u00f3n de car\u00e1cter, competencia y aptitud (CCS), lo que provoca retrasos para que los cuidadores pueden volver a brindar una atenci\u00f3n remunerada. Los requisitos relacionados con las huellas digitales pueden retrasar a\u00fan m\u00e1s la capacidad del cuidador para trabajar, conllevando la p\u00e9rdida de salarios y beneficios, adem\u00e1s de afectar la atenci\u00f3n del cliente durante meses.<strong> La legislaci\u00f3n \u201cLet Us Work\u201d (D\u00e9jennos trabajar) ofrece una soluci\u00f3n que reducir\u00eda los reclamos y agilizar\u00eda el proceso mediante:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>La estandarizaci\u00f3n y aclaraci\u00f3n de los requisitos de la verificaci\u00f3n de antecedentes con huella digital: <\/strong>La estandarizaci\u00f3n ser\u00eda m\u00e1s eficiente, le ahorrar\u00eda dinero al estado y reducir\u00eda los inmensos desaf\u00edos creados por estos requisitos, especialmente para los cuidadores de las zonas rurales, quienes tienen que recorrer largas distancias para llegar a las oficinas que con frecuencia cierran sin previo aviso debido a la escasez de personal.<\/li>\n\n\n\n<li><strong>La eliminaci\u00f3n de las repetidas y engorrosas revisiones de car\u00e1cter, competencia y aptitud (CCS) para estos cuidadores:<\/strong><ul><li>Para los cuidadores que ya completaron la revisi\u00f3n durante su anterior verificaci\u00f3n de antecedentes realizada por el mismo empleador.\u00a0<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Cuidadores que hayan completado un certificado de reintegro y que por los resultados de la verificaci\u00f3n de antecedentes no son autom\u00e1ticamente descalificantes, no se trata de delitos violentos, robo o explotaci\u00f3n financiera, tienen m\u00e1s de 10&nbsp;a\u00f1os de antig\u00fcedad, y no se consideran imprescindibles para una revisi\u00f3n de CCS por parte del DSHS.&nbsp;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"NHhealthcare\">Financiar el programa de atenci\u00f3n m\u00e9dica para essential workers (trabajadores indispensables): Atenci\u00f3n m\u00e9dica asequible para los trabajadores de los nursing homes (asilos para ancianos)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SB 5344 | HB 1523<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los trabajadores de los nursing homes (asilos para ancianos) merecen una atenci\u00f3n m\u00e9dica asequible y de alta calidad, sin embargo el sistema actual deja a muchos trabajadores sin seguro o con miedo de utilizar su seguro de atenci\u00f3n m\u00e9dica debido a los costos. Los empleadores de esta industria no pueden ofrecer un seguro de alta calidad, y los programas de la red de seguridad p\u00fablica existentes con frecuencia no llegan a estos trabajadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La financiaci\u00f3n del programa de atenci\u00f3n m\u00e9dica para essential workers (trabajadores indispensables) para los trabajadores de los nursing homes (asilos para ancianos)<\/strong> incrementar\u00eda la financiaci\u00f3n para los empleadores de alto nivel dedicados a la creaci\u00f3n de un plan de atenci\u00f3n m\u00e9dica asequible y de alta calidad mediante la adici\u00f3n de un pago complementario opcional a la tasa de proveedores de Medicaid de nursing homes (asilos para ancianos) que obtiene un equivalente federal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"WAcares\">Fortalecer nuestros beneficios p\u00fablicos de atenci\u00f3n a largo plazo de WA Cares<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SB 5291 | HB 1415<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>WA Cares es muy importante para nosotros y nuestras familias<\/strong>. La mayor\u00eda de nosotros podr\u00eda necesitar a lo largo de nuestra vida alg\u00fan tipo apoyo relacionado con la atenci\u00f3n a largo plazo para realizar tareas diarias como tomar un ba\u00f1o, comer y transportarnos, pero pr\u00e1cticamente nadie est\u00e1 econ\u00f3micamente preparado para esta realidad. Los votantes protegieron WA Cares en las elecciones de noviembre, y la legislatura debe continuar fortaleciendo el programa mediante la adopci\u00f3n de las recomendaciones de la Comisi\u00f3n LTSS a la legislatura, incluyendo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proporcionar a todos los que tienen una exenci\u00f3n vitalicia una oportunidad limitada de optar de nuevo y unirse a WA Cares<\/li>\n\n\n\n<li>Crear el marco legal correspondiente a un producto de seguro privado de atenci\u00f3n a largo plazo que complemente el WA Cares Fund<\/li>\n\n\n\n<li>Aclarar y simplificar el requisito de adquisici\u00f3n de derechos de por vida a un \u201ctotal de 10&nbsp;a\u00f1os\u201d<\/li>\n\n\n\n<li>Aprobar una modificaci\u00f3n constitucional que permita un mayor rendimiento de la inversi\u00f3n de WA Cares Fund<\/li>\n\n\n\n<li>Recomendaciones adicionales de la Comisi\u00f3n de Servicios y Apoyos a Largo Plazo (LTSS) a la legislatura<\/li>\n\n\n\n<li>Puede encontrar m\u00e1s informaci\u00f3n sobre WA Cares y estas propuestas en WeCareforWACares.org<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ParentProviders\">Pagar a los padres de ni\u00f1os con developmental disabilities (discapacidades del desarrollo)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SB 5211 | HB 1200<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, en Washington, a los padres \u00fanicamente se les permite ser cuidadores empleados para sus hijos con discapacidades cuando estos cumplen 18&nbsp;a\u00f1os. Los padres de menores que brindan el mismo nivel de atenci\u00f3n no son elegibles, lo que crea una situaci\u00f3n desigual. Como resultado, anualmente, el 41&nbsp;% de las horas de cuidado personal de los ni\u00f1os no se utilizan debido a una escasez de cuidadores elegibles. <strong>Este a\u00f1o, la legislatura deber\u00eda corregir esta notoria injusticia permitiendo que los padres de ni\u00f1os menores de 18&nbsp;a\u00f1os elegibles para recibir los servicios de Medicaid sean cuidadores remunerados.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pol\u00edtica que se propone:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Incluir\u00eda todas las horas trabajadas por los padres proveedores en virtud de las exenciones de los servicios domiciliarios y comunitarios<\/li>\n\n\n\n<li>Aplicar\u00eda el mismo entrenamiento, supervisi\u00f3n y requisitos para los padres proveedores de menores que aquellos que se aplican para los padres de hijos adultos<\/li>\n\n\n\n<li>Extender\u00eda la elegibilidad de empleo a los padres de menores, as\u00ed como existe para los padres de hijos adultos<\/li>\n\n\n\n<li>Utilizar\u00eda de forma eficaz los fondos destinados: 1.4&nbsp;millones de horas de cuidado no se utilizan cada a\u00f1o<\/li>\n\n\n\n<li>Reconocer\u00eda a los padres como aquellas personas que mejor saben brindar cuidados y de la forma m\u00e1s segura<\/li>\n\n\n\n<li>Abordar\u00eda los desaf\u00edos desproporcionados a los que se enfrentan los padres debido a la atenci\u00f3n infantil limitada y a los entornos escolares<\/li>\n\n\n\n<li>Empoderar\u00eda a los ni\u00f1os para que escojan al \u201cproveedor de su preferencia\u201d y tengan acceso a los servicios de cuidado necesarios<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1439\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_7678-SEIU-775-edited-scaled.jpg\" alt=\"\" class=\"wp-image-27454\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_7678-SEIU-775-edited-scaled.jpg 2560w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_7678-SEIU-775-edited-300x169.jpg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_7678-SEIU-775-edited-1024x576.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_7678-SEIU-775-edited-768x432.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_7678-SEIU-775-edited-1536x863.jpg 1536w, https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_7678-SEIU-775-edited-2048x1151.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Construir juntos:<br>Campa\u00f1as de solidaridad para la agenda legislativa de Washington para el 2025<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"progressivetaxation\">Volver a nivelar nuestro c\u00f3digo fiscal para financiar los servicios esenciales y hacer que los ricos paguen la parte justa que les corresponde<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Washington sigue siendo uno de los sistemas fiscales m\u00e1s regresivos y ca\u00f3ticos del pa\u00eds. Con un enorme d\u00e9ficit presupuestario, <strong>la legislatura debe aprobar nuevos impuestos progresivos<\/strong> <strong>aplicables a las grandes empresas y a las personas millonarias y multimillonarias con el fin de evitar recortes y financiar programas y servicios esenciales<\/strong>. Muchas pol\u00edticas progresivas eficaces aumentan los ingresos, entre ellas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Impuesto progresivo sobre las n\u00f3minas de los empleadores con mayores ingresos<\/strong><\/li>\n\n\n\n<li><strong>Affordable Homes Act (Ley de Viviendas Asequibles) (\u201cREET 2.0\u201d)<\/strong>: El impuesto especial sobre bienes inmuebles (REET) es un impuesto sobre la venta de bienes inmuebles.<\/li>\n\n\n\n<li><strong>Impuesto sobre la propiedad de carteras de acciones y activos superiores a $250&nbsp;millones (\u201cImpuesto sobre la riqueza\u201d)<\/strong>: Un impuesto del 1&nbsp;% sobre activos financieros como acciones y bonos propiedad de millonarios y multimillonarios.<\/li>\n\n\n\n<li><strong>Recargo de B&amp;O*** a las empresas que facturen m\u00e1s de $1,000&nbsp;millones<\/strong>: El impuesto sobre actividades econ\u00f3micas y de ocupaci\u00f3n (B&amp;O) es un impuesto sobre ingresos brutos basado en los ingresos de una empresa y no en sus ganancias.<\/li>\n\n\n\n<li><strong>Aumentar o ampliar el impuesto a las ganancias de capital para alinearlo con los programas de otros estados: <\/strong>El actual impuesto del 7&nbsp;% sobre el impuesto a las ganancias de capital de Washington se aplica a los beneficios de la venta de activos a largo plazo, como acciones, bonos y participaciones empresariales.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"Rent-Stabilization\">Estabilizaci\u00f3n del alquiler, vivienda asequible y <strong>protecciones a los inquilinos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>HB 1217 | SB 5222<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los legisladores tienen que apoyar pol\u00edticas que protejan a los inquilinos contra los aumentos extremos de los alquileres y las tarifas por atraso, e invertir en m\u00e1s viviendas asequibles, prevenci\u00f3n de la falta de vivienda y asistencia con el alquiler. <\/strong>Los cuidadores, nuestras familias, los adultos mayores y las personas con discapacidad a quienes atendemos merecen vivir en hogares seguros, con buena higiene y asequibles en comunidades pr\u00f3speras. Los costos de la vivienda est\u00e1n afectando todos los rincones de nuestro estado, por lo que este a\u00f1o es necesario tomar una acci\u00f3n integral y audaz. Apoyamos inversiones y pol\u00edticas que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Impidan los aumentos abusivos y extremos de los alquileres y limiten los incrementos anuales<\/li>\n\n\n\n<li>Proporcionen mayores protecciones a los inquilinos, incluida la prevenci\u00f3n de desalojos, medidas de protecci\u00f3n contra los desalojos sin motivo, la obligaci\u00f3n de que los propietarios notifiquen con 6&nbsp;meses de antelaci\u00f3n los aumentos significativos del alquiler, el derecho de los inquilinos a rescindir los contratos de plazo fijo debido al aumento del alquiler, y l\u00edmites a las tarifas por atraso<\/li>\n\n\n\n<li>Inviertan en el Housing Trust Fund (fondo fiduciario para la creaci\u00f3n de viviendas) con el fin de construir y conservar viviendas asequibles, aumentar las inversiones orientadas a la prevenci\u00f3n de la falta de vivienda, las ayudas en efectivo y la asistencia con el alquiler<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"WFTC\">Ampliaci\u00f3n del Working Families Tax Credit (cr\u00e9dito fiscal para las familias trabajadoras)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>HB 1214<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En virtud de la legislaci\u00f3n vigente sobre el Working Families Tax Credit (cr\u00e9dito fiscal para las familias trabajadoras, WFTC), los grupos familiares sin hijos que cumplan los requisitos est\u00e1n sujetos a una restricci\u00f3n de edad. Las personas sin dependientes deben tener al menos 25&nbsp;a\u00f1os y menos de 65 para solicitar el WFTC, lo que significa que la mayor\u00eda de los trabajadores adultos j\u00f3venes y los adultos mayores que trabajan est\u00e1n excluidos de nuestro cr\u00e9dito fiscal estatal. Esta restricci\u00f3n de edad est\u00e1 incluida en el Earned Income Tax Credit (cr\u00e9dito fiscal por ingreso del trabajo) federal en el que se basa el WFTC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exhortamos a la legislatura a ampliar el rango de edad para que todos los contribuyentes de 18 a 24&nbsp;a\u00f1os puedan acceder al WFTC, asegurando que los trabajadores adultos j\u00f3venes se incluyan completamente en la elegibilidad para recibir el cr\u00e9dito<\/strong>. Esto agregar\u00eda 97,500&nbsp;grupos familiares m\u00e1s en Washington, llegando a m\u00e1s adultos j\u00f3venes que viven con bajos ingresos, y aumentar\u00eda el n\u00famero de grupos familiares elegibles en casi un 30&nbsp;%. Esperamos que la legislatura tambi\u00e9n ampl\u00ede el cr\u00e9dito a los adultos mayores que trabajan en una futura sesi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n apoyamos los esfuerzos para promover el intercambio de datos entre las agencias estatales para permitir una mayor aceptaci\u00f3n del cr\u00e9dito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"Unemployment-benefits\">Equidad de los beneficios de desempleo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Seguro por desempleo para los trabajadores en huelga (SB 5041):<\/strong> M\u00e1s de 1 de cada 4&nbsp;estadounidenses tiene menos de $1,000&nbsp;en ahorros, seg\u00fan una encuesta de Forbes realizada en el 2024. En vez de negociar un contrato justo, algunos empleadores se aprovechan de esta inestabilidad econ\u00f3mica para forzar una huelga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Washington deber\u00eda unirse a Nueva York, Nueva Jersey y Maine y permitir que los trabajadores accedan al seguro por desempleo despu\u00e9s de m\u00e1s de dos semanas de huelga para ayudar a igualar las condiciones, disuadir las dificultades econ\u00f3micas como estrategia de negociaci\u00f3n y promover las negociaciones de contratos de buena fe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Seguro por desempleo independientemente del estado migratorio (SB 5026 | HB 1773):<\/strong> 240,000&nbsp;personas viven y trabajan en el estado de Washington sin un estado migratorio federal. Los trabajadores indocumentados constituyen el 5&nbsp;% de la fuerza laboral total y pagan cada a\u00f1o m\u00e1s de mil millones de d\u00f3lares en impuestos estatales y federales. Sin embargo, los trabajadores indocumentados son excluidos para recibir los beneficios de desempleo que mantienen a flote a otros trabajadores entre un empleo y otro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Washington puede hacerlo mejor. Ampliar el seguro por desempleo para incluir a los trabajadores indocumentados es una forma de respetar el valor de cada trabajador, independientemente de nuestro estado migratorio, y permite asegurar nuestro acceso a un apoyo esencial en tiempos de incertidumbre. La aprobaci\u00f3n de este proyecto de ley refuerza el compromiso de nuestro estado con la equidad al rectificar la exclusi\u00f3n de los trabajadores indocumentados de las redes de seguridad a las que contribuimos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"Police-accountability\">Rendici\u00f3n de cuentas de la polic\u00eda para mejorar la seguridad y la confianza de la comunidad<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La reducci\u00f3n de la violencia policial y el aumento de la rendici\u00f3n de cuentas de la polic\u00eda hacen que todas nuestras comunidades sean m\u00e1s seguras y fuertes, apoyan una conexi\u00f3n comunitaria m\u00e1s profunda y promueven los derechos humanos b\u00e1sicos. Apoyamos las <a href=\"https:\/\/wcforpa.org\/2025-priorities\">prioridades de rendici\u00f3n de cuentas de la polic\u00eda para el 2025 de la WA Coalition for Police Accountability<\/a>, entre las que se incluyen la seguridad del tr\u00e1fico para todos, el enjuiciamiento independiente y las investigaciones y reformas del AG.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"Climate-justice\"><strong>Justicia clim\u00e1tica, incluyendo la ayuda con el servicio de energ\u00eda para las personas necesitadas<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos comprometidos con apoyar las prioridades de nuestros aliados en las organizaciones como Front and Centered y BlueGreen Alliance que promueven la justicia clim\u00e1tica y una transici\u00f3n justa en Washington. Tambi\u00e9n apoyamos los esfuerzos para mejorar los programas de ayuda con el servicio de energ\u00eda, porque <strong>todas las personas deber\u00edan tener acceso a una fuente de energ\u00eda confiable, segura y asequible.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"PFML\"><strong>Salario m\u00ednimo de $25, vacaciones pagadas y licencia por duelo<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Salario m\u00ednimo de $25:<\/strong> Aumentar el salario m\u00ednimo protege la seguridad econ\u00f3mica de los trabajadores e impulsa las econom\u00edas locales. La inflaci\u00f3n ha reducido el poder adquisitivo de los salarios desde el 2020. El ajuste a la inflaci\u00f3n de $15 en el 2012 es equivalente a $20 en el 2023. Sin un cambio legislativo, el salario m\u00ednimo de Washington no alcanzar\u00e1 los $20 hasta al menos 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Beneficios econ\u00f3micos:<\/strong> Los salarios m\u00e1s altos reducen la rotaci\u00f3n y aumentan la productividad, lo que beneficia a los empleadores. Los trabajadores con salarios m\u00e1s altos pueden gastar m\u00e1s en los negocios locales, apoyando el crecimiento econ\u00f3mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vacaciones pagadas:<\/strong> El 79&nbsp;% de los trabajadores del sector privado de Estados Unidos tienen vacaciones pagadas, sin embargo los trabajadores con salarios m\u00e1s bajos tienen menos posibilidades de acceder a ellas. Solo el 55&nbsp;% de los trabajadores de servicios y el 40&nbsp;% de los trabajadores a tiempo parcial tienen vacaciones pagadas, en comparaci\u00f3n con el 92&nbsp;% de los trabajadores administrativos y profesionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Licencia por duelo pagada:<\/strong> Muchos trabajadores no reciben un pago por licencia durante los momentos cr\u00edticos de la vida. Es tiempo de garantizar que los trabajadores tengan acceso a vacaciones pagadas y licencias por duelo, protegiendo su bienestar y apoyando a sus familias durante los momentos dif\u00edciles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"PFML\">Cerrar la brecha de protecci\u00f3n laboral en las licencias m\u00e9dicas familiares pagadas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En virtud de la ley estatal vigente, la mitad de los trabajadores de Washington, que requieren un pago por el programa de licencias m\u00e9dicas familiares, no pueden recibir un pago sin poner en riesgo su empleo. Acceder a la licencia pagada no solo podr\u00eda resultar en el despido, sino que tambi\u00e9n incluye perder el acceso a la atenci\u00f3n m\u00e9dica en momentos en los que el trabajador o su familia enfrentan una grave enfermedad. Una investigaci\u00f3n reciente de la University of Washington encontr\u00f3 que las mujeres, los trabajadores de color y aquellos sin t\u00edtulos universitarios tienen menos probabilidades de optar a un permiso con protecci\u00f3n del empleo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Apoyamos la legislaci\u00f3n que ampl\u00eda la protecci\u00f3n del empleo a todos los trabajadores en licencia que lleven en su cargo al menos 90&nbsp;d\u00edas calendario<\/strong>. El proyecto de ley tambi\u00e9n reducir\u00eda el umbral de solicitud de 8&nbsp;a 4&nbsp;horas de ausencia del trabajo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ParentProviders\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Prioridades relacionadas con el progreso: Construir un futuro mejor para los cuidadores y las comunidades Nuestra misi\u00f3n es unir las fuerzas de todos los cuidadores con el fin de mejorar nuestras vidas y las de aquellas personas bajo nuestro cuidado, as\u00ed como marcar el camino hacia un mundo m\u00e1s justo y equitativo. No somos un [&hellip;]<\/p>\n","protected":false},"author":1699,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-27170","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agenda legislativa de Washington para el 2025 - SEIU 775<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/es\/2025waleg\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda legislativa de Washington para el 2025 - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Prioridades relacionadas con el progreso: Construir un futuro mejor para los cuidadores y las comunidades Nuestra misi\u00f3n es unir las fuerzas de todos los cuidadores con el fin de mejorar nuestras vidas y las de aquellas personas bajo nuestro cuidado, as\u00ed como marcar el camino hacia un mundo m\u00e1s justo y equitativo. No somos un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/es\/2025waleg\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-07T22:00:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2025waleg\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2025waleg\\\/\",\"name\":\"Agenda legislativa de Washington para el 2025 - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2025waleg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2025waleg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_4586-Kale-16x9-1-1024x576.jpeg\",\"datePublished\":\"2025-01-06T22:18:22+00:00\",\"dateModified\":\"2025-02-07T22:00:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2025waleg\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/es\\\/2025waleg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2025waleg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_4586-Kale-16x9-1-1024x576.jpeg\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_4586-Kale-16x9-1-1024x576.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/2025waleg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda legislativa de Washington para el 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenda legislativa de Washington para el 2025 - SEIU 775","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/es\/2025waleg\/","og_locale":"es_ES","og_type":"article","og_title":"Agenda legislativa de Washington para el 2025 - SEIU 775","og_description":"Prioridades relacionadas con el progreso: Construir un futuro mejor para los cuidadores y las comunidades Nuestra misi\u00f3n es unir las fuerzas de todos los cuidadores con el fin de mejorar nuestras vidas y las de aquellas personas bajo nuestro cuidado, as\u00ed como marcar el camino hacia un mundo m\u00e1s justo y equitativo. No somos un [&hellip;]","og_url":"https:\/\/seiu775.org\/es\/2025waleg\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2025-02-07T22:00:25+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/es\/2025waleg\/","url":"https:\/\/seiu775.org\/es\/2025waleg\/","name":"Agenda legislativa de Washington para el 2025 - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seiu775.org\/es\/2025waleg\/#primaryimage"},"image":{"@id":"https:\/\/seiu775.org\/es\/2025waleg\/#primaryimage"},"thumbnailUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-1024x576.jpeg","datePublished":"2025-01-06T22:18:22+00:00","dateModified":"2025-02-07T22:00:25+00:00","breadcrumb":{"@id":"https:\/\/seiu775.org\/es\/2025waleg\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/es\/2025waleg\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/es\/2025waleg\/#primaryimage","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-1024x576.jpeg","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2025\/01\/IMG_4586-Kale-16x9-1-1024x576.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/es\/2025waleg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"Agenda legislativa de Washington para el 2025"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/27170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/1699"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=27170"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/27170\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=27170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":25974,"date":"2024-04-10T19:39:43","date_gmt":"2024-04-10T19:39:43","guid":{"rendered":"https:\/\/seiu775.org\/preparacin-para-emergencias\/"},"modified":"2026-03-11T10:28:54","modified_gmt":"2026-03-11T17:28:54","slug":"emergency-preparedness","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/emergency-preparedness\/","title":{"rendered":"Preparaci&oacute;n para emergencias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n se presentan recursos para que cuide de usted y de su cliente durante emergencias, como terremotos, incendios y fr\u00edo extremo.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/\">Visite: Recursos para mantenerse a salvo en caso de calor extremo y humo por incendios forestales<\/a><\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"#alerts\">Consulte: C\u00f3mo registrarse para recibir alertas de emergencia en su condado<\/a><\/strong><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Prep\u00e1rese y prepare a sus clientes para situaciones de emergencia<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/url.us.m.mimecastprotect.com\/s\/RVtXCL9W0pTk6Vjuos7IyR6Zi?domain=cl.s11.exct.net\">Inscr\u00edbase en los nuevos cursos de Preparaci\u00f3n ante Emergencias<\/a><\/strong> SEIU\u00a0775\u00a0Benefits\u00a0Group ahora ofrece seis cursos de Continuing Education (Educaci\u00f3n continua) en l\u00ednea sobre la preparaci\u00f3n para emergencias relacionadas con el clima. Los cursos en l\u00ednea est\u00e1n disponibles para inscripci\u00f3n en ocho idiomas: ingl\u00e9s, \u00e1rabe, coreano, ruso, chino simplificado, espa\u00f1ol, ucraniano y vietnamita.\u00a0Animamos a los cuidadores a tomar estos cursos para protegerse a s\u00ed mismos, a sus clientes y a sus seres queridos.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/doh.wa.gov\/emergencies\/be-prepared-be-safe\/get-ready\"><strong>C\u00f3mo preparar un kit de emergencia para cualquier situaci\u00f3n o cat\u00e1strofe<\/strong><\/a> (WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.ready.gov\/disability\"><strong>Preparaci\u00f3n para cat\u00e1strofes para personas con discapacidades<\/strong><\/a> Disponible en \u00e1rabe, espa\u00f1ol, franc\u00e9s, criollo haitiano, japon\u00e9s, coreano, ruso, tagalo, vietnamita y chino<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/doh.wa.gov\/emergencies\/be-prepared-be-safe\/get-ready\">C\u00f3mo prepararse para las emergencias<\/a><\/strong> (WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n<p class=\"wp-block-paragraph\">Lista de verificaci\u00f3n de preparaci\u00f3n para cuidadores, disponible en <a href=\"https:\/\/www.redcross.org\/content\/dam\/redcross\/get-help\/how-to-prepare\/Caregivers-AARP-Checklist_-_R2_FINAL.pdf\">ingl\u00e9s<\/a> y <a href=\"https:\/\/www.redcross.org\/content\/dam\/redcross\/get-help\/how-to-prepare\/Caregivers-AARP-Checklist_-_Spanish_R2_FINAL.pdf\">espa\u00f1ol<\/a> (Cruz Roja)<\/p>\n\n<p class=\"wp-block-paragraph\">Preparaci\u00f3n para cat\u00e1strofes para adultos mayores, disponible en <a href=\"https:\/\/www.redcross.org\/content\/dam\/redcross\/get-help\/how-to-prepare\/Older_Adults_Disaster_Prep_1Pager_11012022.pdf\">ingl\u00e9s<\/a> y <a href=\"https:\/\/www.redcross.org\/content\/dam\/redcross\/get-help\/how-to-prepare\/SP_Older_Adults_Disaster_Prep_1Pager_11012022.pdf\">espa\u00f1ol<\/a> (Cruz Roja)<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.redcross.org\/get-help\/how-to-prepare-for-emergencies\/types-of-emergencies.html\"><strong>Consejos de preparaci\u00f3n para emergencias<\/strong><\/a> (Cruz Roja)<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/doh.wa.gov\/emergencies\/be-prepared-be-safe\/severe-weather-and-natural-disasters\/earthquakes\">Recursos en caso de terremotos en Washington<\/a><\/strong> (WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/des.mt.gov\/Preparedness\/Earthquakes\"><strong>Recursos en caso de terremotos en Montana<\/strong><\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.earthquakecountry.org\/library\/ShakeOut_Earthquake_Guide_Disabilities_AFN.pdf\">Gu\u00eda contra terremotos<\/a><\/strong> para adultos mayores y personas con discapacidad<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/doh.wa.gov\/emergencies\/be-prepared-be-safe\/severe-weather-and-natural-disasters\/landslides-and-mudflows\"><strong>Deslizamientos de tierra: c\u00f3mo prepararse<\/strong><\/a> (WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/doh.wa.gov\/emergencies\/be-prepared-be-safe\/severe-weather-and-natural-disasters\/shelter-place\">C\u00f3mo refugiarse en el lugar<\/a> <\/strong>(WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n<p class=\"wp-block-paragraph\">Prepare un <a href=\"https:\/\/www.ready.gov\/sites\/default\/files\/2021-02\/ready_checklist.pdf\"><strong>kit de suministros para cat\u00e1strofes<\/strong><\/a> (Ready.Gov)<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"extreme-cold\">Qu\u00e9 hacer en caso de fr\u00edo extremo<\/h3>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/doh.wa.gov\/emergencies\/be-prepared-be-safe\/severe-weather-and-natural-disasters\/cold-weather\"><strong>Tormentas de invierno en Washington: c\u00f3mo prepararse<\/strong><\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Consejos de seguridad para el invierno en Montana: <a href=\"https:\/\/montana811.org\/2019\/01\/01\/winter-safety-tips\/\"><strong>Montana811<\/strong><\/a> y Safe <a href=\"https:\/\/www.safemt.com\/resources\/safe-winter-driving\/\"><strong>Winter Driving<\/strong><\/a> (Conducir de forma segura en invierno)<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"flooding\">Qu\u00e9 hacer antes, durante y despu\u00e9s de una inundaci\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.fema.gov\/flood-maps\/know-your-risk\/homeowners\">Know Your Flood Risk<\/a> <\/strong>(Conozca su riesgo de inundaci\u00f3n) (FEMA)<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.fema.gov\/sites\/default\/files\/documents\/fema_flood-protect-brochure_2023.pdf\"><strong>Protect Your Property from Flooding<\/strong><\/a> (Proteja su propiedad de las inundaciones) (FEMA)<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/des.mt.gov\/Preparedness\/Flood-Resources\"><strong>Recursos en caso de inundaciones en Montana<\/strong><\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/doh.wa.gov\/emergencies\/be-prepared-be-safe\/severe-weather-and-natural-disasters\/floods\"><strong>Recursos en caso de inundaciones en Washington<\/strong><\/a> (WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"alerts\">Inscr\u00edbase para recibir alertas de emergencia en el estado de Washington<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"642\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-1024x642.png\" alt=\"\" class=\"wp-image-26126\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-1024x642.png 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-300x188.png 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-768x482.png 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-1536x963.png 1536w, https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-2048x1284.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<ul class=\"wp-block-list\">\n<li>Condado de Asotin: <strong><a href=\"https:\/\/www.co.asotin.wa.us\/206\/Emergency-Services\">Inscr\u00edbase en NotifyMe<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Benton: <a href=\"https:\/\/www.bces.wa.gov\/emergency-management\/code-red\">Inscr\u00edbase en Code-Red<\/a><\/li>\n\n\n\n<li>Condado de Chelan: <a href=\"https:\/\/www.co.chelan.wa.us\/emergency-management\"><strong>Inscr\u00edbase en Everbridge<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Clallum:<strong> <a href=\"https:\/\/www.clallamcountywa.gov\/226\/Emergency-Management\">Inscr\u00edbase en Everbridge<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Clark: <a href=\"https:\/\/clark.wa.gov\/public-health\/public-health-emergency-response\"><strong>Inscr\u00edbase en Smart911 a trav\u00e9s de CRESA911<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Columbia: <a href=\"https:\/\/www.columbiaco.com\/77\/Emergency-Management\"><strong>Inscr\u00edbase en Code-Red<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Cowlitz: <a href=\"https:\/\/www.co.cowlitz.wa.us\/196\/Emergency-Management\"><strong>Inscr\u00edbase en Hyper-reach<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Douglas:<strong> <a href=\"https:\/\/www.douglascountywa.net\/231\/Emergency-Management\">Inscr\u00edbase en Everbridge<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Ferry: <a href=\"https:\/\/www.ferry-county.com\/government\/board_of_commissioners\/emergency_management.php\"><strong>Inscr\u00edbase en el Alert Ferry County System (Sistema de alertas del condado de Ferry)<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Franklin: <a href=\"https:\/\/franklinem.org\/emergency-preparedness-for-you-and-your-family\/\"><strong>Inscr\u00edbase en Code-Red<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Garfield: <strong><a href=\"https:\/\/www.garfieldcountywa.gov\/em\">Inscr\u00edbase en AlertSense<\/a><\/strong><\/li>\n\n\n\n<li>Grays Harbor: <a href=\"https:\/\/www.graysharbor.us\/departments\/emergency_management\/index.php\"><strong>Inscr\u00edbase en Smart911<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Grant: <a href=\"https:\/\/www.grantcountywa.gov\/directory.aspx?did=135\"><strong>Inscr\u00edbase en NotifyMe<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Island: <a href=\"https:\/\/www.islandcountywa.gov\/170\/Department-of-Emergency-Management\"><strong>Inscr\u00edbase en myAlerts<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Jefferson: <a href=\"https:\/\/www.co.jefferson.wa.us\/950\/Dept-of-Emergency-Management\"><strong>Inscr\u00edbase en NIXLE<\/strong><\/a><\/li>\n\n\n\n<li>Condado de King: <strong><a href=\"https:\/\/kingcounty.gov\/en\/dept\/executive-services\/governance-leadership\/emergency-management\">Inscr\u00edbase en el Alert Ferry County System (Sistema de alertas del condado de Ferry)<\/a>. <\/strong>En Seattle,<strong> <a href=\"https:\/\/alert.seattle.gov\/\">inscr\u00edbase en ALERT Seattle.<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Kitsap: <a href=\"https:\/\/www.kitsapdem.com\/\"><strong>Inscr\u00edbase en Kitsap ALERT<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Kittitas: <strong><a href=\"https:\/\/www.co.kittitas.wa.us\/sheriff\/emergency.aspx\">Inscr\u00edbase en Everbridge<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Klickitat:<a href=\"https:\/\/www.klickitatcounty.org\/249\/Emergency-Management\"> <strong>Inscr\u00edbase en Smart911<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Lewis: <strong><a href=\"https:\/\/lewiscountywa.gov\/departments\/emergency-management\/emergency-preparedness\/\">Inscr\u00edbase en Lewis County Alert (Sistema de alerte del condado de Lewis)<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Lincoln: <a href=\"https:\/\/www.co.lincoln.wa.us\/sheriff\/county-emergency-plans\/\"><strong>Inscr\u00edbase en AlertSense<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Okanogan: <strong><a href=\"https:\/\/www.okanogancounty.org\/government\/emergency_management\/index.php\">Inscr\u00edbase en Everbridge<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Mason: <a href=\"https:\/\/masoncountywa.gov\/dem\/index.php\"><strong>Inscr\u00edbase en Code-Red<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Pacific: <a href=\"https:\/\/pcema.info\/\"><strong>Inscr\u00edbase en Hyper-reach<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Pend Orielle: <a href=\"https:\/\/www.pendoreilleco.org\/emergency-management\"><strong>Inscr\u00edbase en NIXLE<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Pierce: <a href=\"https:\/\/www.piercecountywa.gov\/945\/Personal-Preparedness\"><strong>Inscr\u00edbase en PC-Alert<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Skagit:<strong> <a href=\"https:\/\/www.skagitcounty.net\/Departments\/EmergencyManagement\/main.htm\">Inscr\u00edbase en Code-Red<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Skamania: <a href=\"https:\/\/www.skamaniacounty.org\/departments-offices\/emergency-management\"><strong>Inscr\u00edbase en Hyper-reach<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Snohomish:<strong> <a href=\"https:\/\/snohomishcountywa.gov\/719\/Personal-Preparedness\">Gu\u00edas de preparaci\u00f3n personal<\/a><\/strong><\/li>\n\n\n\n<li>Condado de Spokane: <a href=\"https:\/\/www.spokanecounty.org\/1752\/Individuals\"><strong>Inscr\u00edbase en Alert Spokane<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Stevens: <a href=\"https:\/\/www.stevenscountywa.gov\/pview.aspx?id=21025&amp;catid=25\"><strong>Inscr\u00edbase en Hyper-reach<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Thurston: <a href=\"https:\/\/www.thurstoncountywa.gov\/departments\/emergency-management\/emergency-information\"><strong>Inscr\u00edbase en TC-Alert<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Wahkiakum: <a href=\"https:\/\/www.co.wahkiakum.wa.us\/201\/Alert-Notifications\"><strong>Inscr\u00edbase en ALERT Wahkiakum<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Walla Walla: <a href=\"https:\/\/www.co.walla-walla.wa.us\/residents\/emergency_management\/index.php\"><strong>Inscr\u00edbase en Citizen ALERT (c\u00f3digo QR en l\u00ednea)<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Whatcom: <a href=\"https:\/\/www.whatcomcounty.us\/201\/Emergency-Management\"><strong>Inscr\u00edbase en Whatcom Unified ALERT Sense (Sistema de alerta unificado de Whatcom)<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Whitman: <a href=\"https:\/\/www.whitmancounty.org\/264\/Emergency-Management\"><strong>Inscr\u00edbase en Everbridge<\/strong><\/a><\/li>\n\n\n\n<li>Condado de Yakima: <a href=\"https:\/\/www.yakimacounty.us\/350\/Emergency-Management\"><strong>Inscr\u00edbase en ALERT Yakima<\/strong><\/a><\/li>\n\n\n\n<li>A nivel estatal: <a href=\"https:\/\/mil.wa.gov\/alerts#local\"><strong>Washington Emergency Department (Departamento de Emergencias de Washington)<\/strong><\/a><\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"extreme-cold\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n se presentan recursos para que cuide de usted y de su cliente durante emergencias, como terremotos, incendios y fr\u00edo extremo. Visite: Recursos para mantenerse a salvo en caso de calor extremo y humo por incendios forestales Consulte: C\u00f3mo registrarse para recibir alertas de emergencia en su condado Prep\u00e1rese y prepare a sus clientes [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-25974","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preparaci&oacute;n para emergencias - SEIU 775<\/title>\n<meta name=\"description\" content=\"Recursos para que cuide de usted y de su cliente durante emergencias, como terremotos, incendios y fr\u00edo extremo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/ko\/emergency-preparedness\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preparaci&oacute;n para emergencias - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Recursos para que cuide de usted y de su cliente durante emergencias, como terremotos, incendios y fr\u00edo extremo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/ko\/emergency-preparedness\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T17:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/ko\\\/emergency-preparedness\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/ko\\\/emergency-preparedness\\\/\",\"name\":\"Preparaci&oacute;n para emergencias - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/ko\\\/emergency-preparedness\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/ko\\\/emergency-preparedness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Alertsystems-1024x642.png\",\"datePublished\":\"2024-04-10T19:39:43+00:00\",\"dateModified\":\"2026-03-11T17:28:54+00:00\",\"description\":\"Recursos para que cuide de usted y de su cliente durante emergencias, como terremotos, incendios y fr\u00edo extremo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/ko\\\/emergency-preparedness\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/ko\\\/emergency-preparedness\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/ko\\\/emergency-preparedness\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Alertsystems-1024x642.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Alertsystems-1024x642.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/ko\\\/emergency-preparedness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preparaci&oacute;n para emergencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preparaci&oacute;n para emergencias - SEIU 775","description":"Recursos para que cuide de usted y de su cliente durante emergencias, como terremotos, incendios y fr\u00edo extremo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/","og_locale":"es_ES","og_type":"article","og_title":"Preparaci&oacute;n para emergencias - SEIU 775","og_description":"Recursos para que cuide de usted y de su cliente durante emergencias, como terremotos, incendios y fr\u00edo extremo","og_url":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2026-03-11T17:28:54+00:00","og_image":[{"width":2560,"height":1605,"url":"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/","url":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/","name":"Preparaci&oacute;n para emergencias - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/#primaryimage"},"image":{"@id":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/#primaryimage"},"thumbnailUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-1024x642.png","datePublished":"2024-04-10T19:39:43+00:00","dateModified":"2026-03-11T17:28:54+00:00","description":"Recursos para que cuide de usted y de su cliente durante emergencias, como terremotos, incendios y fr\u00edo extremo","breadcrumb":{"@id":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/ko\/emergency-preparedness\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/#primaryimage","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-1024x642.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/05\/Alertsystems-1024x642.png"},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/ko\/emergency-preparedness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"Preparaci&oacute;n para emergencias"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/25974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=25974"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/25974\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=25974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":25973,"date":"2024-04-10T19:39:42","date_gmt":"2024-04-10T19:39:42","guid":{"rendered":"https:\/\/seiu775.org\/resources-extreme-heat-wildfire-smoke\/"},"modified":"2025-05-30T10:43:23","modified_gmt":"2025-05-30T17:43:23","slug":"resources-extreme-heat-wildfire-smoke-es","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/","title":{"rendered":"C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El calor extremo nos afecta a todos, especialmente en lugares donde no hab\u00edamos tenido que prepararnos para afrontarlo hasta hace poco. <strong>Tenga precauci\u00f3n cuando se encuentre en condiciones clim\u00e1ticas extremas, y consulte los recursos que se indican a continuaci\u00f3n, as\u00ed como los sitios web de su condado o estado, para obtener consejos adicionales.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfBusca recursos en su condado, incluyendo ayuda con el servicio de energ\u00eda y servicios de climatizaci\u00f3n? <a href=\"https:\/\/seiu775.org\/es\/climate-es\/\"><strong>Visite nuestra p\u00e1gina de preparaci\u00f3n para el clima.<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote-1024x1024.jpg\" alt=\"\" class=\"wp-image-26824\" style=\"width:600px\" srcset=\"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote-1024x1024.jpg 1024w, https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote-300x300.jpg 300w, https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote-150x150.jpg 150w, https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote-768x768.jpg 768w, https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/kingcounty.gov\/en\/-\/media\/king-county\/depts\/dph\/documents\/safety-injury-prevention\/emergency-preparedness\/stay-safe-in-the-heat-en.pdf\"><strong>C\u00f3mo mantenerse a salvo en el calor: <\/strong><\/a>gu\u00eda para prevenir las enfermedades causadas por el calor durante per\u00edodos con condiciones clim\u00e1ticas calurosas, especialmente para las personas con mayor riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/mil.wa.gov\/asset\/5e4d629c71bf7\">C\u00f3mo preparar su casa para un incendio forestal<\/a> \u2013 <\/strong>disponible en ingl\u00e9s y espa\u00f1ol<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.epa.gov\/natural-disasters\/extreme-heat\"><strong>C\u00f3mo prepararse para el calor extremo<\/strong><\/a> (U.S. Environmental Protection Agency [Agencia de Protecci\u00f3n Medioambiental de EE.&nbsp;UU.])<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.epa.gov\/air-research\/smoke-ready-toolbox-wildfires#OnlineTrainingForHealthProfessionals\">Entrenamiento en l\u00ednea para profesionales de la salud sobre c\u00f3mo mantener seguros a sus pacientes<\/a><\/strong> (U.S. Environmental Protection Agency [Agencia de Protecci\u00f3n Medioambiental de EE.&nbsp;UU.])<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.airnow.gov\/sites\/default\/files\/2020-02\/reduce-health-risks-with-wildfire-smoke-508.pdf\">Reduzca los riesgos para la salud en zonas con humo de incendios forestales<\/a> <\/strong>(U.S. Environmental Protection Agency [Agencia de Protecci\u00f3n Medioambiental de EE.&nbsp;UU.])<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.pscleanair.gov\/525\/DIY-Air-Filter\"><strong>Filtro de aire para ventilador de caja de bricolaje:<\/strong><\/a> \u00a1la eficacia de los filtros de aire no se mide por su precio! Todo lo que necesita es un ventilador de caja y el tipo de filtro de aire que podr\u00eda encontrar para un horno de una <strong><a href=\"https:\/\/pscleanair.gov\/DocumentCenter\/View\/4080\/Filter-Fan-Instructions\">soluci\u00f3n de bricolaje<\/a>.<\/strong> \u00bfTiene preguntas sobre su eficacia? Consulte este <strong><a href=\"https:\/\/pscleanair.gov\/DocumentCenter\/View\/4079\/Filter-Fan-Fact-Sheet\">enlace<\/a>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/naes.agnt.unr.edu\/PMS\/Pubs\/1510_2007_90.pdf?utm_source=publications&amp;utm_medium=pub-download&amp;utm_campaign=pub-link-clicks&amp;utm_content=2977\"><strong>Lista de verificaci\u00f3n para evacuaciones en caso de incendios forestales<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Recursos en Washington<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Durante los per\u00edodos de calor extremo, es posible que se establezcan centros de enfriamiento en su \u00e1rea, gratuitos para el p\u00fablico. Marque 2-1-1 o utilice el recurso en l\u00ednea estatal\u202f<strong><a href=\"https:\/\/search.wa211.org\/search?location=&amp;query=TH-2600.1900-180&amp;query_type=taxonomy&amp;query_label=Extreme+Heat+Cooling+Centers\">para encontrar centros de enfriamiento cerca de usted.<\/a> <\/strong>Se ofrece asistencia en el idioma. (WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/doh.wa.gov\/emergencies\/be-prepared-be-safe\/severe-weather-and-natural-disasters\/extreme-heat\/hot-weather-precautions\">Precauciones en condiciones clim\u00e1ticas calientes<\/a> <\/strong>(WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/doh.wa.gov\/community-and-environment\/air-quality\/smoke-fires\">Preguntas frecuentes sobre el humo<\/a><\/strong> (WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/doh.wa.gov\/community-and-environment\/air-quality\/smoke-fires\/partner-toolkit\">Indicaciones en caso de incendios forestales <\/a><\/strong>(WA Department of Health [Departamento de Salud de Washington])<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/enviwa.ecology.wa.gov\/home\/map\">\u00cdndice de calidad del aire<\/a><\/strong> (Department of Ecology [Departamento de Ecolog\u00eda])<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/enviwa.ecology.wa.gov\/home\/text\/421#Forecast\">Pron\u00f3stico respecto al humo<\/a><\/strong> (Department of Ecology [Departamento de Ecolog\u00eda])<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Recursos en Montana<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.safemt.com\/wp-content\/uploads\/2021\/07\/safemt_TakeTheSizzleOut.pdf\"><strong>Seguridad en caso de calor extremo en Montana<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.mtfireinfo.org\/\">Recursos en caso de incendios en Montana<\/a>. <\/strong>Tambi\u00e9n puede ver un <a href=\"https:\/\/youtu.be\/zSsK_lmBrzk\">video<\/a> que muestra c\u00f3mo preparar su casa, utilizando ense\u00f1anzas derivadas del Incendio Elmo ocurrido en julio del 2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El calor extremo nos afecta a todos, especialmente en lugares donde no hab\u00edamos tenido que prepararnos para afrontarlo hasta hace poco. Tenga precauci\u00f3n cuando se encuentre en condiciones clim\u00e1ticas extremas, y consulte los recursos que se indican a continuaci\u00f3n, as\u00ed como los sitios web de su condado o estado, para obtener consejos adicionales.&nbsp; \u00bfBusca recursos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-25973","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales - SEIU 775<\/title>\n<meta name=\"description\" content=\"Recursos para cuidarse y cuidar a su cliente en caso de calor extremo y humo por incendios forestales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Recursos para cuidarse y cuidar a su cliente en caso de calor extremo y humo por incendios forestales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T17:43:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/resources-extreme-heat-wildfire-smoke-es\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/es\\\/resources-extreme-heat-wildfire-smoke-es\\\/\",\"name\":\"C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/resources-extreme-heat-wildfire-smoke-es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/resources-extreme-heat-wildfire-smoke-es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Paris-M.-Climate-Quote-1024x1024.jpg\",\"datePublished\":\"2024-04-10T19:39:42+00:00\",\"dateModified\":\"2025-05-30T17:43:23+00:00\",\"description\":\"Recursos para cuidarse y cuidar a su cliente en caso de calor extremo y humo por incendios forestales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/resources-extreme-heat-wildfire-smoke-es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/es\\\/resources-extreme-heat-wildfire-smoke-es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/resources-extreme-heat-wildfire-smoke-es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Paris-M.-Climate-Quote-1024x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Paris-M.-Climate-Quote-1024x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/es\\\/resources-extreme-heat-wildfire-smoke-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales - SEIU 775","description":"Recursos para cuidarse y cuidar a su cliente en caso de calor extremo y humo por incendios forestales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/","og_locale":"es_ES","og_type":"article","og_title":"C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales - SEIU 775","og_description":"Recursos para cuidarse y cuidar a su cliente en caso de calor extremo y humo por incendios forestales","og_url":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2025-05-30T17:43:23+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/","url":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/","name":"C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/#primaryimage"},"image":{"@id":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/#primaryimage"},"thumbnailUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote-1024x1024.jpg","datePublished":"2024-04-10T19:39:42+00:00","dateModified":"2025-05-30T17:43:23+00:00","description":"Recursos para cuidarse y cuidar a su cliente en caso de calor extremo y humo por incendios forestales","breadcrumb":{"@id":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/#primaryimage","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote-1024x1024.jpg","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2024\/10\/Paris-M.-Climate-Quote-1024x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/es\/resources-extreme-heat-wildfire-smoke-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"C&oacute;mo mantenerse a salvo en caso de calor extremo y humo por incendios forestales"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/25973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=25973"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/25973\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=25973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":24885,"date":"2023-07-06T02:21:26","date_gmt":"2023-07-06T02:21:26","guid":{"rendered":"http:\/\/seiu775.org\/2023endorsements_spa\/"},"modified":"2023-07-06T02:21:43","modified_gmt":"2023-07-06T02:21:43","slug":"2023endorsements_spa","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/2023endorsements_spa\/","title":{"rendered":"Respaldos en las elecciones de Washington del 2023"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/seiu775.org\/2023endorsements_rus\" data-type=\"URL\" data-id=\"seiu775.org\/2023endorsements_rus\">\u041d\u0430\u0436\u043c\u0438\u0442\u0435 \u0437\u0434\u0435\u0441\u044c \u0434\u043b\u044f \u043f\u0440\u043e\u0441\u043c\u043e\u0442\u0440\u0430 \u043d\u0430 \u0440\u0443\u0441\u0441\u043a\u043e\u043c \u044f\u0437\u044b\u043a\u0435<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/seiu775.org\/2023endorsements\/\" data-type=\"page\" data-id=\"24843\">Click here to read in English<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/seiu775.org\/2023endorsements_chs\/\" data-type=\"page\" data-id=\"24873\">\u70b9\u51fb\u8fd9\u91cc\u67e5\u770b\u4e2d\u6587<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/seiu775.org\/2023endorsements_kor\/\" data-type=\"page\" data-id=\"24875\">\ud55c\uad6d\uc5b4\ub85c \ubcf4\ub824\uba74 \uc5ec\uae30\ub97c \ud074\ub9ad\ud558\uc138\uc694<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/seiu775.org\/2023endorsements_vie\/\" data-type=\"page\" data-id=\"24877\">B\u1ea5m v\u00e0o \u0111\u00e2y \u0111\u1ec3 xem b\u1eb1ng ti\u1ebfng Vi\u1ec7t<\/a><\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Los cuidadores de SEIU 775 en todo el estado de Washington se unieron, entrevistaron a los candidatos a cargos p\u00fablicos en Washington y est\u00e1n orgullosos de respaldar a los siguientes candidatos.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfEst\u00e1 registrado para votar?<a href=\"https:\/\/voter.votewa.gov\/WhereToVote.aspx\" data-type=\"URL\" data-id=\"https:\/\/voter.votewa.gov\/WhereToVote.aspx\"> <strong>Haga clic aqu\u00ed para iniciar sesi\u00f3n en VoteWA y comprobar si est\u00e1 registrado para votar y asegurarse de que su direcci\u00f3n est\u00e1 actualizada<\/strong><\/a><\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfNo tiene la boleta? Solicite una nueva boleta en <a href=\"https:\/\/voter.votewa.gov\/WhereToVote.aspx\" data-type=\"URL\" data-id=\"https:\/\/voter.votewa.gov\/WhereToVote.aspx\">vote.wa.gov<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Inicie sesi\u00f3n en <a href=\"https:\/\/voter.votewa.gov\/WhereToVote.aspx\" data-type=\"URL\" data-id=\"https:\/\/voter.votewa.gov\/WhereToVote.aspx\">voter.votewa.gov<\/a> y haga clic en \u201cVoters\u2019 Guide\u201d (Gu\u00eda para votantes) en el men\u00fa de la izquierda para obtener una lista completa de candidatos y temas en su boleta electoral.<\/p>\n\n<p class=\"wp-block-paragraph\">Si desea ayudar a elegir a los candidatos respaldados por los cuidadores, comun\u00edquese con su organizador local.<\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"wp-block-paragraph\"><strong>Auburn<\/strong><br\/>James Jeyaraj<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bellevue<\/strong><br\/>John Stokes<br\/>Mohammed Malakoutian<br\/>Janice Zahn<br\/>David Hamilton<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Burien<\/strong><br\/>Brittany Williams<br\/>Patricia Hudson<br\/>Krystal Marx<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Edmonds<\/strong><br\/>Mike Nelson<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Federal Way<\/strong><br\/>Denise Yum<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fife<\/strong><br\/>Bryan Yambe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>King County<\/strong><br\/>Girmay Zahilay<br\/>Jorge L. Bar\u00f3n<br\/>Claudia Balducci<br\/>Teresa Mosqueda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Port of Seattle<\/strong><br\/>Sam Cho<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Public Hospital<\/strong><br\/>Anthony Berkley<br\/>Amber Wise<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Renton<\/strong><br\/>Kim-Khanh Van<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SeaTac<\/strong><br\/>Elizabeth Greninger<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Seattle<\/strong><br\/>Tammy Morales<br\/>Alex Hudson<br\/>Nilu Jenks<br\/>Dan Strauss<br\/>Andrew Lewis<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Snohomish County<\/strong><br\/>Dave Somer<br\/>Megan Dunn<br\/>Susanna Johnson<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Spokane<\/strong><br\/>Lisa Brown<br\/>Betsy Wilkerson<br\/>Lindsey Shaw<br\/>Paul Dillon<br\/>Esteban Herevia<br\/>Kitty Klitzke<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tacoma<\/strong><br\/>Olgy Diaz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Yakima<\/strong><br\/>Dulce Guti\u00e9rrez<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"wp-block-paragraph\"><br\/>City of Auburn Council Position 3<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>City of Bellevue Council \u2013 Position 1<br\/>City of Bellevue Council \u2013 Position 3<br\/>City of Bellevue Council \u2013 Position 5<br\/>City of Bellevue Council \u2013 Position 7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>City of Burien Council Position 2<br\/>City of Burien Council Position 4<br\/>City of Burien Council Position 6<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>Mayor of the City of Edmonds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>City of Federal Way Council &#8211; Position 7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>City of Fife Council District 1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>King County Council District 2<br\/>King County Council District 4<br\/>King County Council District 6<br\/>King County Council District 8<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>Port of Seattle Commissioner 2<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>Public Hospital \u2013 District 1 (Valley Hospital)<br\/>Public Hospital \u2013 District 2 (Evergreen Medical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>City of Renton Council &#8211; Position 7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>SeaTac City Council District 3<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>City of Seattle Council District 2<br\/>City of Seattle Council District 3<br\/>City of Seattle Council District 5<br\/>City of Seattle Council District 6<br\/>City of Seattle Council District 7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>Snohomish County Executive<br\/>Snohomish County Council District 2<br\/>Snohomish County Sheriff<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>Mayor of the City of Spokane<br\/>President of the Council of Spokane<br\/>City of Spokane Council Position 1<br\/>City of Spokane Council Position 2<br\/>City of Spokane Council Position 3 (dual)<br\/>City of Spokane Council Position 3 (dual)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>City of Tacoma Council at-large Position 7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br\/>City of Yakima Council District 1<\/p>\n<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n puede consultar esta lista relacionada con importantes temas econ\u00f3micos, incluyendo los candidatos respaldados por muchas organizaciones: progressvotersguide.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cuidadores de SEIU 775 en todo el estado de Washington se unieron, entrevistaron a los candidatos a cargos p\u00fablicos en Washington y est\u00e1n orgullosos de respaldar a los siguientes candidatos. \u00bfEst\u00e1 registrado para votar? Haga clic aqu\u00ed para iniciar sesi\u00f3n en VoteWA y comprobar si est\u00e1 registrado para votar y asegurarse de que su [&hellip;]<\/p>\n","protected":false},"author":1699,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-24885","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Respaldos en las elecciones de Washington del 2023 - SEIU 775<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/2023endorsements_spa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Respaldos en las elecciones de Washington del 2023 - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Los cuidadores de SEIU 775 en todo el estado de Washington se unieron, entrevistaron a los candidatos a cargos p\u00fablicos en Washington y est\u00e1n orgullosos de respaldar a los siguientes candidatos. \u00bfEst\u00e1 registrado para votar? Haga clic aqu\u00ed para iniciar sesi\u00f3n en VoteWA y comprobar si est\u00e1 registrado para votar y asegurarse de que su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/2023endorsements_spa\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T02:21:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/2023endorsements_spa\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/2023endorsements_spa\\\/\",\"name\":\"Respaldos en las elecciones de Washington del 2023 - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"datePublished\":\"2023-07-06T02:21:26+00:00\",\"dateModified\":\"2023-07-06T02:21:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/2023endorsements_spa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/2023endorsements_spa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/2023endorsements_spa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Respaldos en las elecciones de Washington del 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Respaldos en las elecciones de Washington del 2023 - SEIU 775","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/2023endorsements_spa\/","og_locale":"es_ES","og_type":"article","og_title":"Respaldos en las elecciones de Washington del 2023 - SEIU 775","og_description":"Los cuidadores de SEIU 775 en todo el estado de Washington se unieron, entrevistaron a los candidatos a cargos p\u00fablicos en Washington y est\u00e1n orgullosos de respaldar a los siguientes candidatos. \u00bfEst\u00e1 registrado para votar? Haga clic aqu\u00ed para iniciar sesi\u00f3n en VoteWA y comprobar si est\u00e1 registrado para votar y asegurarse de que su [&hellip;]","og_url":"https:\/\/seiu775.org\/2023endorsements_spa\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2023-07-06T02:21:43+00:00","twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/2023endorsements_spa\/","url":"https:\/\/seiu775.org\/2023endorsements_spa\/","name":"Respaldos en las elecciones de Washington del 2023 - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"datePublished":"2023-07-06T02:21:26+00:00","dateModified":"2023-07-06T02:21:43+00:00","breadcrumb":{"@id":"https:\/\/seiu775.org\/2023endorsements_spa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/2023endorsements_spa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/2023endorsements_spa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"Respaldos en las elecciones de Washington del 2023"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/24885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/1699"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=24885"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/24885\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=24885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":24096,"date":"2023-07-05T22:58:41","date_gmt":"2023-07-05T22:58:41","guid":{"rendered":"http:\/\/seiu775.org\/?page_id=24096"},"modified":"2026-05-07T10:16:24","modified_gmt":"2026-05-07T17:16:24","slug":"wacares","status":"publish","type":"page","link":"https:\/\/seiu775.org\/es\/wacares\/","title":{"rendered":"WA Cares"},"content":{"rendered":"\n<div class=\"wp-block-group content-with-video has-gray-background-color has-background is-layout-flex wp-block-group-is-layout-flex\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" style=\"font-size:34px\">Beneficio de atenci\u00f3n a largo plazo del estado de Washington<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de nosotros no estamos preparados para afrontar el momento en que necesitemos atenci\u00f3n a largo plazo.\u00a0Por eso, los cuidadores lucharon en el 2019 para aprobar <a href=\"https:\/\/wacaresfund.wa.gov\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>WA Cares<\/strong><\/a>, el primer programa de seguro social para atenci\u00f3n a largo plazo del pa\u00eds. <strong>Los beneficios de WA Cares comenzar\u00e1n el 1.\u00ba de julio del 2026.<\/strong> \u00a1Estamos un paso m\u00e1s cerca de nuestra meta! Queremos que todas las personas tengan acceso a atenci\u00f3n a largo plazo asequible y de alta calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a WA Cares, las personas elegibles en el estado de Washington recibir\u00e1n hasta $36,500 para servicios de atenci\u00f3n a largo plazo, incluyendo cuidado en el hogar, atenci\u00f3n domiciliaria y atenci\u00f3n en nursing home (asilo para ancianos). WA Cares tambi\u00e9n cubre adaptaciones en el hogar, como barras de apoyo, transporte a citas m\u00e9dicas, entrega de alimentos a domicilio, dispositivos de asistencia, suministros de atenci\u00f3n y otros servicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/wacaresfund.wa.gov\/\" target=\"_blank\" rel=\"noreferrer noopener\">Obtenga m\u00e1s informaci\u00f3n sobre los beneficios de WA <\/a><a href=\"https:\/\/wacaresfund.wa.gov\/\">Cares en WACaresFund.wa.gov<\/a>. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con WA Cares, se realiza un peque\u00f1o descuento de n\u00f3mina de $0.58 por cada $100 que se gana. Despu\u00e9s de contribuir durante algunos a\u00f1os, las personas elegibles pueden acceder hasta a $36,500 (cantidad que aumenta con el tiempo) para pagar la atenci\u00f3n a largo plazo, incluida la atenci\u00f3n domiciliaria de familiares o cuidadores profesionales o la atenci\u00f3n en nursing homes (asilos para ancianos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/wecareforwacares.org\/\" target=\"_blank\">Conozca m\u00e1s sobre por qu\u00e9 los cuidadores y otros apoyan WA Cares en WeCareforWACares.org<\/a>.<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"https:\/\/wecareforwacares.org\/wp-content\/uploads\/2022\/12\/ImpactReport.WACaresFund.2022.pdf\" target=\"_blank\"><strong>Obtenga aqu\u00ed m\u00e1s informaci\u00f3n sobre el impacto que tendr\u00e1 WA Cares en su comunidad.<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Alyssa | Home Care Support\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/v_kDDRzDxwM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-group sidebar-menu is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<h4 class=\"wp-block-heading has-black-color has-text-color\">CAMPA\u00d1AS DE SEIU\u00a0775<\/h4>\n\n\n<nav class=\"has-text-color has-purple-color items-justified-left is-vertical wp-block-navigation is-content-justification-left is-layout-flex wp-container-core-navigation-is-layout-afab3323 wp-block-navigation-is-layout-flex\" aria-label=\"Campaigns\"><ul class=\"wp-block-navigation__container has-text-color has-purple-color items-justified-left is-vertical wp-block-navigation\"><li class=\"wp-block-navigation-item wp-block-navigation-link\"><a class=\"wp-block-navigation-item__content\"  href=\"https:\/\/seiu775.org\/cdwa\/\"><span class=\"wp-block-navigation-item__label\"><strong>CDWA<\/strong><\/span><\/a><\/li><li class=\"wp-block-navigation-item wp-block-navigation-link\"><a class=\"wp-block-navigation-item__content\"  href=\"https:\/\/seiu775.org\/hadit\/\"><span class=\"wp-block-navigation-item__label\"><strong>HADit<\/strong><\/span><\/a><\/li><\/ul><\/nav><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<div class=\"wp-block-group ip-guidelines news alignfull has-white-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group ip-guidelines-wrap is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-large-font-size\">Noticias<\/h2>\n\n\n<div class=\"wp-container-12 wp-block-query news-listing-compaign\">\n        <ul class=\"wp-block-post-template\"><li class=\"wp-block-post post-31200 post type-post status-publish format-standard hentry category-news\">\n                <h4 class=\"wp-container-8 has-text-color has-purple-color wp-block-post-title\">\n                  <a href=\"https:\/\/seiu775.org\/es\/immigrant-care-cuts\/\" target=\"_self\" rel=\"\">Federal Cuts to Immigrant Care\u00a0<\/a><\/h4>\n\n                <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Because of cruel cuts to care included in Trump&#8217;s HR 1, the \u201cBig Ugly Bill,\u201d thousands of ...<\/p><\/div>\n                \n              <\/li><li class=\"wp-block-post post-31165 post type-post status-publish format-standard hentry category-news\">\n                <h4 class=\"wp-container-8 has-text-color has-purple-color wp-block-post-title\">\n                  <a href=\"https:\/\/seiu775.org\/es\/as-wa-caregiver-union-pushes-for-pay-hike-state-seeks-wage-freeze\/\" target=\"_self\" rel=\"\">As WA caregiver union pushes for pay hike, state seeks wage freeze<\/a><\/h4>\n\n                <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Washington State Standard | August 17, 2026 Negotiations between the two sides will affect pay for a...<\/p><\/div>\n                \n              <\/li><li class=\"wp-block-post post-31155 post type-post status-publish format-standard hentry category-news\">\n                <h4 class=\"wp-container-8 has-text-color has-purple-color wp-block-post-title\">\n                  <a href=\"https:\/\/seiu775.org\/es\/ukrainian-refugee-looming-healthcare-cuts-for-wa-a-catastrophe\/\" target=\"_self\" rel=\"\">Ukrainian refugee: Looming healthcare cuts for WA a 'catastrophe'<\/a><\/h4>\n\n                <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Public News Service | August 19, 2026 Immigrant rights groups in Washington are urging Gov. Bob Ferg...<\/p><\/div>\n                \n              <\/li><li class=\"wp-block-post post-31097 post type-post status-publish format-standard hentry category-news\">\n                <h4 class=\"wp-container-8 has-text-color has-purple-color wp-block-post-title\">\n                  <a href=\"https:\/\/seiu775.org\/es\/backgroundchecks\/\" target=\"_self\" rel=\"\">&ldquo;Let Us Work&rdquo; (D&eacute;jennos trabajar): Mejoras en la verificaci&oacute;n de antecedentes de los cuidadores domiciliarios&nbsp;<\/a><\/h4>\n\n                <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Los cuidadores del estado de Washington se enfrentaron a desaf\u00edos significativos debido al proceso ...<\/p><\/div>\n                \n              <\/li><li class=\"wp-block-post post-31088 post type-post status-publish format-standard hentry category-news\">\n                <h4 class=\"wp-container-8 has-text-color has-purple-color wp-block-post-title\">\n                  <a href=\"https:\/\/seiu775.org\/es\/opinion-im-a-caregiver-sen-dan-sullivan-wont-answer-my-questions-about-medicaid-cuts\/\" target=\"_self\" rel=\"\">Opinion: I\u2019m a caregiver. Sen. Dan Sullivan won\u2019t answer my questions about Medicaid cuts.<\/a><\/h4>\n\n                <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Anchorage Daily News | August 6, 2026 I\u2019ve been a caregiver for my family members for almost 28 ye...<\/p><\/div>\n                \n              <\/li><li class=\"wp-block-post post-31063 post type-post status-publish format-standard hentry category-news\">\n                <h4 class=\"wp-container-8 has-text-color has-purple-color wp-block-post-title\">\n                  <a href=\"https:\/\/seiu775.org\/es\/press-release-seiu-775-montana-members-endorse-independent-u-s-senate-candidate-seth-bodnar\/\" target=\"_self\" rel=\"\">Press Release: SEIU 775 Montana Members Endorse Independent U.S. Senate Candidate Seth Bodnar<\/a><\/h4>\n\n                <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">HELENA, Mont. (August 4, 2026) \u2014 Following a member-led endorsement process that included intervie...<\/p><\/div>\n                \n              <\/li><\/ul>\n      <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Beneficio de atenci\u00f3n a largo plazo del estado de Washington La mayor\u00eda de nosotros no estamos preparados para afrontar el momento en que necesitemos atenci\u00f3n a largo plazo.\u00a0Por eso, los cuidadores lucharon en el 2019 para aprobar WA Cares, el primer programa de seguro social para atenci\u00f3n a largo plazo del pa\u00eds. Los beneficios de [&hellip;]<\/p>\n","protected":false},"author":688,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-new-members.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-24096","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WA Cares - SEIU 775<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seiu775.org\/wacares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WA Cares - SEIU 775\" \/>\n<meta property=\"og:description\" content=\"Beneficio de atenci\u00f3n a largo plazo del estado de Washington La mayor\u00eda de nosotros no estamos preparados para afrontar el momento en que necesitemos atenci\u00f3n a largo plazo.\u00a0Por eso, los cuidadores lucharon en el 2019 para aprobar WA Cares, el primer programa de seguro social para atenci\u00f3n a largo plazo del pa\u00eds. Los beneficios de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seiu775.org\/wacares\/\" \/>\n<meta property=\"og:site_name\" content=\"SEIU 775\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seiu775\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T17:16:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seiu775\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/wacares\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wacares\\\/\",\"name\":\"WA Cares - SEIU 775\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\"},\"datePublished\":\"2023-07-05T22:58:41+00:00\",\"dateModified\":\"2026-05-07T17:16:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/wacares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seiu775.org\\\/wacares\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/wacares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seiu775.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WA Cares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#website\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"name\":\"SEIU775\",\"description\":\"We&#039;re Stronger Together\",\"publisher\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seiu775.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#organization\",\"name\":\"SEIU775\",\"url\":\"https:\\\/\\\/seiu775.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seiu775.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo.png\",\"width\":126,\"height\":126,\"caption\":\"SEIU775\"},\"image\":{\"@id\":\"https:\\\/\\\/seiu775.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seiu775\",\"https:\\\/\\\/x.com\\\/seiu775\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRnCbqnYM3ZaGYHUZQiG3Ug\",\"https:\\\/\\\/www.instagram.com\\\/seiu775\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seiu-775nw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WA Cares - SEIU 775","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seiu775.org\/wacares\/","og_locale":"es_ES","og_type":"article","og_title":"WA Cares - SEIU 775","og_description":"Beneficio de atenci\u00f3n a largo plazo del estado de Washington La mayor\u00eda de nosotros no estamos preparados para afrontar el momento en que necesitemos atenci\u00f3n a largo plazo.\u00a0Por eso, los cuidadores lucharon en el 2019 para aprobar WA Cares, el primer programa de seguro social para atenci\u00f3n a largo plazo del pa\u00eds. Los beneficios de [&hellip;]","og_url":"https:\/\/seiu775.org\/wacares\/","og_site_name":"SEIU 775","article_publisher":"https:\/\/www.facebook.com\/seiu775","article_modified_time":"2026-05-07T17:16:24+00:00","twitter_card":"summary_large_image","twitter_site":"@seiu775","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seiu775.org\/wacares\/","url":"https:\/\/seiu775.org\/wacares\/","name":"WA Cares - SEIU 775","isPartOf":{"@id":"https:\/\/seiu775.org\/#website"},"datePublished":"2023-07-05T22:58:41+00:00","dateModified":"2026-05-07T17:16:24+00:00","breadcrumb":{"@id":"https:\/\/seiu775.org\/wacares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seiu775.org\/wacares\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/seiu775.org\/wacares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seiu775.org\/es\/"},{"@type":"ListItem","position":2,"name":"WA Cares"}]},{"@type":"WebSite","@id":"https:\/\/seiu775.org\/#website","url":"https:\/\/seiu775.org\/","name":"SEIU775","description":"We&#039;re Stronger Together","publisher":{"@id":"https:\/\/seiu775.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seiu775.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seiu775.org\/#organization","name":"SEIU775","url":"https:\/\/seiu775.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/","url":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","contentUrl":"https:\/\/seiu775.org\/wp-content\/uploads\/2020\/07\/logo.png","width":126,"height":126,"caption":"SEIU775"},"image":{"@id":"https:\/\/seiu775.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seiu775","https:\/\/x.com\/seiu775","https:\/\/www.youtube.com\/channel\/UCRnCbqnYM3ZaGYHUZQiG3Ug","https:\/\/www.instagram.com\/seiu775\/","https:\/\/www.linkedin.com\/company\/seiu-775nw\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 04:31:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/24096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/users\/688"}],"replies":[{"embeddable":true,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/comments?post=24096"}],"version-history":[{"count":0,"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/pages\/24096\/revisions"}],"wp:attachment":[{"href":"https:\/\/seiu775.org\/es\/wp-json\/wp\/v2\/media?parent=24096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]